{"id":14431,"date":"2023-07-07T17:27:53","date_gmt":"2023-07-07T17:27:53","guid":{"rendered":"https:\/\/eco-nnect.com\/?p=14431"},"modified":"2023-08-13T19:37:50","modified_gmt":"2023-08-13T19:37:50","slug":"soberania-indigena-la-polemica-del-marco-temporal","status":"publish","type":"post","link":"https:\/\/eco-nnect.com\/es\/soberania-indigena-la-polemica-del-marco-temporal\/","title":{"rendered":"Soberan\u00eda ind\u00edgena: la pol\u00e9mica del Marco Temporal"},"content":{"rendered":"<span class=\"rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Reading Time: <\/span> <span class=\"rt-time\">21<\/span> <span class=\"rt-label rt-postfix\">min<\/span><\/span><p><span style=\"font-weight: 400;\">Raposa-Serra do Sol, en el Estado de Roraima, al norte de Brasil, es una cadena de biomas conocida localmente como <a href=\"https:\/\/www.equatorinitiative.org\/wp-content\/uploads\/2022\/12\/Roraima-Case-Study-English-FNL.pdf\">lavrado<\/a>. En esta regi\u00f3n, el lavrado abarca praderas, sabanas esteparias, matorrales y zonas de peque\u00f1os bosques, que forman parte de una delicada red interconectada de ecosistemas que nutren y sustentan lo que a menudo se denomina la Amazonia. Estos ecosistemas se mantienen gracias a un clima mayoritariamente h\u00famedo, con dos estaciones claras: la h\u00fameda, de abril a noviembre; y la seca, de diciembre a marzo. Durante los meses h\u00famedos aparecen lagos estacionales que conectan con r\u00edos m\u00e1s grandes, cauces que act\u00faan como barreras contra el fuego. En a\u00f1os secos, durante los fen\u00f3menos de <a href=\"https:\/\/www.bbc.com\/news\/science-environment-64192508\">El Ni\u00f1o<\/a>, estos canales que antes estaban llenos de agua se convierten en corredores de fuego.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los lavrados est\u00e1n protegidos en gran medida en Brasil debido a la demarcaci\u00f3n de los territorios ind\u00edgenas -que abarcan m\u00e1s del 46% del estado de Roraima-, incluida Raposa-Serra do Sol, la Tierra del Zorro y Monta\u00f1a del Sol, que comprende m\u00e1s de 1,7 millones de hect\u00e1reas. Raposa-Serra do Sol fue convertida en ley brasile\u00f1a por el Presidente Luis In\u00e1cio Lula da Silva el 15 de abril de 2005. Se extiende a lo largo de la frontera con Venezuela y Guyana, y alberga a unos 58.000 habitantes de nueve comunidades ind\u00edgenas diferentes: Macuxi, Wapichana, Taurepang, Ingarik\u00f3, Wai-Wai, Yanomami, Ye&#8217;kuana, Patamona y Sapar\u00e1. El modo de vida de estas comunidades se centra en su medio ambiente, donde cazan, cultivan y pescan.<\/span><\/p>\n<figure id=\"attachment_14254\" aria-describedby=\"caption-attachment-14254\" style=\"width: 1600px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-14254\" src=\"https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/1600px-Raposa_Serra_do_Sol_Nascer_do_sol.jpg\" alt=\"\" width=\"1600\" height=\"1091\" srcset=\"https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/1600px-Raposa_Serra_do_Sol_Nascer_do_sol.jpg 1600w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/1600px-Raposa_Serra_do_Sol_Nascer_do_sol-600x409.jpg 600w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/1600px-Raposa_Serra_do_Sol_Nascer_do_sol-300x205.jpg 300w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/1600px-Raposa_Serra_do_Sol_Nascer_do_sol-1024x698.jpg 1024w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/1600px-Raposa_Serra_do_Sol_Nascer_do_sol-768x524.jpg 768w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/1600px-Raposa_Serra_do_Sol_Nascer_do_sol-1536x1047.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><figcaption id=\"caption-attachment-14254\" class=\"wp-caption-text\">Raposa-Serra do Sol.<\/figcaption><\/figure>\n<p><span style=\"font-weight: 400;\">El proceso de demarcaci\u00f3n surgi\u00f3 a trav\u00e9s de <a href=\"https:\/\/www.epochtimes.com.br\/interesse-estrangeiro-na-demarcacao-de-terras-indigenas-no-brasil-entrevista-exclusiva-parte%E2%80%931_186207.html\">discusiones comunitarias en 1983<\/a>, que se desarrollaron en las Asambleas de Tuxauas y condujeron a la formaci\u00f3n del <a href=\"https:\/\/cir.org.br\/site\/\">Conselho Ind\u00edgena de Roraima<\/a> (Consejo Ind\u00edgena de Roraima, CIR) en 1990. El CIR reuni\u00f3 a personas de las comunidades Ingarik\u00f3, Macuxi, Patamona, Sapar\u00e1, Taurepang, Wai-Wai, Wapichana, Yanomami y Ye&#8217;kuana, que defend\u00edan su respectiva soberan\u00eda colectiva. Durante sus dos primeras d\u00e9cadas de funcionamiento, el CIR se centr\u00f3 en la lucha por la demarcaci\u00f3n de las tierras de los pueblos Ingaric\u00f3, Macuxi, Patamona, Tuarepang y Wapichana, que abarca casi la mitad de Roraima y es una de las zonas de mayor conservaci\u00f3n de cualquier Estado de la Amazonia brasile\u00f1a.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Esta es la historia de la relaci\u00f3n simbi\u00f3tica entre los pueblos ind\u00edgenas y su tierra, pero tambi\u00e9n es la historia de la forma en que esta tierra, y la tierra en general, es percibida desde un punto de vista econ\u00f3mico y pol\u00edtico por la comunidad brasile\u00f1a e internacional.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Raposa-Serra do Sol es rica en biodiversidad -y en significado cultural para los pueblos que desde hace mucho tiempo la llaman su hogar- y abundante en los llamados recursos naturales: yacimientos de oro, diamante, titanio, amatista, caol\u00edn, zinc, cobre, niobio, casiterita, cristal, diatomita, barita, molibdeno, niobio, piedra caliza, agua mineral y posiblemente, aunque no est\u00e1 confirmado, petr\u00f3leo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La larga resistencia de los pueblos ind\u00edgenas de Raposa-Serra do Sol queda ejemplificada por el <a href=\"https:\/\/acervo.socioambiental.org\/sites\/default\/files\/documents\/yal00067_en.pdf\">bien documentado inter\u00e9s<\/a> de los <a href=\"https:\/\/amazonwatch.org\/news\/2022\/0519-illegal-miners-terrorize-brazils-yanomami-communities\">mineros oportunistas<\/a> por el <a href=\"https:\/\/eco-nnect.com\/the-last-forest\/\">territorio vecino de los Yanomami.<\/a><\/span><\/p>\n<p><span style=\"font-weight: 400;\">La invasi\u00f3n de mineros a trav\u00e9s del territorio Yanomami comenz\u00f3 tras la ca\u00edda de la larga <a href=\"https:\/\/en.wikipedia.org\/wiki\/Military_dictatorship_in_Brazil\">dictadura militar<\/a> de Brasil. El Gobierno Federal de la dictadura hab\u00eda fomentado la creencia de que la Amazonia traer\u00eda el desarrollo econ\u00f3mico a Brasil. Una <a href=\"https:\/\/g1.globo.com\/politica\/blog\/octavio-guedes\/post\/2021\/04\/23\/bolsonaro-sem-clima-para-contar-ditadura-queria-transformar-amazonia-em-pasto.ghtml\">publicidad<\/a> de 1972 afirmaba que la Amazonia era donde \u00abla tierra es barata y su granja puede tener todos los pastos que su ganado necesita\u00bb. A esta afirmaci\u00f3n contribu\u00edan los incentivos fiscales y la financiaci\u00f3n para apoyar a quienes buscaban esta oportunidad propuesta.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Impulsada por el descubrimiento de oro en la base de Serra Pelada, en el Estado de Par\u00e1, una fiebre minera se extendi\u00f3 por el norte de Brasil hasta el territorio Yanomami. Impulsados por la ambici\u00f3n personal, los mineros se animaron con la creencia de que la sociedad brasile\u00f1a se fortalecer\u00eda con la extracci\u00f3n de los recursos naturales que supuestamente ofrec\u00eda la selva amaz\u00f3nica. 40.000 mineros buscaban oro y casiterita en territorio Yanomami, viendo al pueblo Yanomami como <a href=\"https:\/\/www.survivalinternational.org\/tribes\/yanomami\">obst\u00e1culos a superar<\/a> en el camino hacia la fortuna.<\/span><\/p>\n<figure id=\"attachment_14270\" aria-describedby=\"caption-attachment-14270\" style=\"width: 530px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-14270\" src=\"https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/Bolsonaro_1986_28cropped29.jpg\" alt=\"\" width=\"530\" height=\"826\" srcset=\"https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/Bolsonaro_1986_28cropped29.jpg 530w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/Bolsonaro_1986_28cropped29-192x300.jpg 192w\" sizes=\"(max-width: 530px) 100vw, 530px\" \/><figcaption id=\"caption-attachment-14270\" class=\"wp-caption-text\">Jair Bolsonaro de joven.<\/figcaption><\/figure>\n<p><span style=\"font-weight: 400;\">En la ciudad de Sa\u00fade, en el Estado de Bah\u00eda, un joven teniente del ej\u00e9rcito brasile\u00f1o, Jair Bolsonaro, <a href=\"https:\/\/www1.folha.uol.com.br\/poder\/2017\/05\/1884332-bolsonaro-era-agressivo-e-tinha-excessiva-ambicao-diz-ficha-militar.shtml#=\">buscaba oro<\/a> mientras estaba de vacaciones durante su servicio activo. Sus superiores recibieron la noticia de estas vacaciones -que disfrut\u00f3 con tres tenientes y dos sargentos paracaidistas-, lo que dio lugar a una evaluaci\u00f3n interna que tach\u00f3 al joven Bolsonaro de tener una \u00abambici\u00f3n desmedida\u00bb. Esto puede haber sido cierto -la ambici\u00f3n de Bolsonaro era evidente cuando dej\u00f3 el ej\u00e9rcito para comenzar su larga carrera pol\u00edtica-, pero tambi\u00e9n reflejaba la opini\u00f3n de que la miner\u00eda equival\u00eda a riqueza, tanto personal como colectiva, que era fomentada por el gobierno brasile\u00f1o y estaba ganando m\u00e1s popularidad en la sociedad brasile\u00f1a. Un <a href=\"https:\/\/www.culturalsurvival.org\/publications\/cultural-survival-quarterly\/demarcation-and-then-what-brazil-takes-step-its-commitment\">estudio realizado en 1987 por antrop\u00f3logos brasile\u00f1os<\/a> revel\u00f3 que en un 30% de los territorios ind\u00edgenas hab\u00edan entrado mineros independientes y en un 70%, empresas mineras.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A medida que los mineros se establec\u00edan en territorio Yanomami, aumentaba la violencia contra la comunidad Yanomami, lo que provoc\u00f3 la muerte de alrededor del <a href=\"https:\/\/www.survivalinternational.org\/tribes\/yanomami\">veinte por ciento<\/a> de su poblaci\u00f3n en siete a\u00f1os. El l\u00edder espiritual y pol\u00edtico Yanomami Davi Kopenawa, junto con <a href=\"https:\/\/www.survivalinternational.org\/\">Survival International<\/a> y la <a href=\"http:\/\/www.proyanomami.org.br\/v0904\/index.asp?pag=htm&amp;url=http:\/\/www.proyanomami.org.br\/base_ini.htm\">Comiss\u00e3o Pr\u00f3-Yanomami (CCPY)<\/a>, lideraron una campa\u00f1a internacional para la demarcaci\u00f3n y protecci\u00f3n del territorio Yanomami mediante el <a href=\"http:\/\/www.proyanomami.org.br\/v0904\/index.asp?pag=htm&amp;url=\/apy\/YU_ing\/4.htm\">Decreto Interministerial n\u00ba 160<\/a> del 13 de septiembre de 1988, que declaraba 8.216.925 hect\u00e1reas de tierra como posesi\u00f3n permanente del Pueblo Yanomami.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El Decreto se promulg\u00f3 en v\u00edsperas de la ratificaci\u00f3n de la nueva <a href=\"https:\/\/www.globalhealthrights.org\/wp-content\/uploads\/2013\/09\/Brazil-constitution-English.pdf\">Constituci\u00f3n de la Rep\u00fablica Federativa de Brasil<\/a>, que garantizaba los Derechos de los Pueblos Ind\u00edgenas articulando la legitimidad del Estado brasile\u00f1o para legislar sobre ellos. Esto se logr\u00f3 a trav\u00e9s del Cap\u00edtulo VIII, y espec\u00edficamente el Art\u00edculo 231, que define el territorio Ind\u00edgena como la tierra \u00abtradicionalmente ocupada&#8230; en la que viven de forma permanente&#8230; utilizada para sus actividades productivas, las indispensables para la preservaci\u00f3n de los recursos ambientales necesarios para su bienestar y para su reproducci\u00f3n f\u00edsica y cultural, de acuerdo con sus usos, costumbres y tradiciones\u00bb. El art\u00edculo 231 articul\u00f3 que el Estado brasile\u00f1o demarcar\u00e1, proteger\u00e1 y har\u00e1 respetar los territorios Ind\u00edgenas; que los Pueblos Ind\u00edgenas tendr\u00e1n el uso exclusivo de los recursos emanados del suelo, r\u00edos y lagos existentes dentro de sus territorios; que los minerales debajo de sus territorios s\u00f3lo podr\u00e1n ser prospectados y explotados con autorizaci\u00f3n del Congreso Nacional; que el desalojo de los Pueblos Ind\u00edgenas de sus tierras est\u00e1 prohibido, excepto por el Congreso Nacional (en caso de cat\u00e1strofe, epidemia o en inter\u00e9s de la soberan\u00eda de Brasil); y cualquier acto con vistas a la ocupaci\u00f3n, dominio o posesi\u00f3n de sus tierras es \u00abnulo y sin valor\u00bb, a menos que se haya realizado con \u00abinter\u00e9s p\u00fablico relevante\u00bb del Estado brasile\u00f1o y a trav\u00e9s de una ley complementaria. El art\u00edculo 232 otorgaba a los pueblos ind\u00edgenas de Brasil el derecho a demandar para defender sus derechos e intereses.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La presentaci\u00f3n por parte de los Yanomami del Decreto n\u00ba 160, con el apoyo de los Derechos contenidos en la nueva Constituci\u00f3n, inspir\u00f3 un largo proceso que implic\u00f3 una <a href=\"https:\/\/www.culturalsurvival.org\/publications\/cultural-survival-quarterly\/demarcation-and-then-what-brazil-takes-step-its-commitment\">importante oposici\u00f3n<\/a>, la cual llev\u00f3 a miembros del Congreso de Roraima a presentar una demanda contra el proceso, y al Gobernador del Estado de Amazonas a amenazar con enviar a la polic\u00eda estatal a disparar contra cualquier agente de la Fondazione Nazionale dell&#8217;Indio (FUNAI) que intentara demarcar el territorio. Jair Bolsonaro, ahora diputado federal por R\u00edo de Janeiro, <a href=\"https:\/\/oglobo.globo.com\/blogs\/bernardo-mello-franco\/coluna\/2023\/01\/bolsonaro-se-vingou-dos-ianomamis.ghtml\">pregunt\u00f3<\/a> al Congreso Federal: \u00abesa zona es la m\u00e1s rica del pa\u00eds, \u00bfpor qu\u00e9 crear all\u00ed una reserva ind\u00edgena?\u00bb Tambi\u00e9n afirm\u00f3 que los Yanomami eran una amenaza para la seguridad nacional y podr\u00edan iniciar un movimiento separatista. Esto se hac\u00eda eco de las palabras del Sertanista <a href=\"https:\/\/oglobo.globo.com\/blogs\/bernardo-mello-franco\/coluna\/2023\/01\/bolsonaro-se-vingou-dos-ianomamis.ghtml\">Orlando Villas-B\u00f4as<\/a>, quien, en la d\u00e9cada de 1970, articul\u00f3 la <a href=\"https:\/\/www.summitpost.org\/raposa-serra-do-sol-indigenous-land-rr-brazil\/1063746\" class=\"broken_link\">creencia<\/a> de que la creaci\u00f3n de reservas ind\u00edgenas en zonas fronterizas supon\u00eda un <a href=\"https:\/\/terrasindigenas.org.br\/noticia\/62911\" class=\"broken_link\">riesgo<\/a> para la integridad del territorio brasile\u00f1o y que los misioneros ten\u00edan el objetivo encubierto de establecer organismos independientes o semi-independientes que fragmentar\u00edan el control del Gobierno brasile\u00f1o sobre la Amazonia. A pesar de estas objeciones, el Decreto n\u00ba 160 se convirti\u00f3 finalmente en ley brasile\u00f1a en 1992 y los numerosos mineros que operaban en territorio Yanomami fueron expulsados temporalmente.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Durante este periodo, los pueblos ind\u00edgenas de Raposa-Serra do Sol tambi\u00e9n lucharon contra las invasiones de los mineros, los ganaderos, los productores de arroz y el ej\u00e9rcito brasile\u00f1o, que <a href=\"http:\/\/www.wald.org\/cimi\/2001\/cimie490.htm\">construy\u00f3<\/a> cuarteles militares en la zona y llev\u00f3 a cabo actividades de adiestramiento cerca de la frontera con Guyana. Se <a href=\"https:\/\/www.survivalinternational.org\/news\/152\">robaron o destruyeron<\/a> tierras ind\u00edgenas, y muchos pueblos ind\u00edgenas sufrieron <a href=\"https:\/\/www.survivalinternational.org\/tribes\/raposa\">agresiones f\u00edsicas<\/a>. Estas tensiones se produjeron en parte por el avance del proceso de demarcaci\u00f3n de Raposa-Serra do Sol, mediante el mapeo realizado por la FUNAI y la ratificaci\u00f3n del territorio por el presidente Lula da Silva a trav\u00e9s del Decreto 534\/2005, lo que llev\u00f3 al Gobierno Federal a intentar desalojar a los ocupantes no ind\u00edgenas que quedaban, que se resistieron, quemando puentes y atacando centros comunitarios, lo que provoc\u00f3 violentos enfrentamientos que culminaron con el <a href=\"http:\/\/www.forestpeoples.org\/sites\/fpp\/files\/news\/2010\/08\/brazil_rf_release_raposa_aug08_eng.pdf\">asesinato a tiros de diez ind\u00edgenas<\/a> el 5 de mayo de 2008.<\/span><\/p>\n<figure id=\"attachment_14281\" aria-describedby=\"caption-attachment-14281\" style=\"width: 2560px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-14281\" src=\"https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/2560px-Presidente_Lula_visita_Raposa_Serra_do_Sol.jpg\" alt=\"\" width=\"2560\" height=\"1644\" srcset=\"https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/2560px-Presidente_Lula_visita_Raposa_Serra_do_Sol.jpg 2560w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/2560px-Presidente_Lula_visita_Raposa_Serra_do_Sol-600x385.jpg 600w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/2560px-Presidente_Lula_visita_Raposa_Serra_do_Sol-300x193.jpg 300w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/2560px-Presidente_Lula_visita_Raposa_Serra_do_Sol-1024x658.jpg 1024w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/2560px-Presidente_Lula_visita_Raposa_Serra_do_Sol-768x493.jpg 768w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/2560px-Presidente_Lula_visita_Raposa_Serra_do_Sol-1536x986.jpg 1536w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/2560px-Presidente_Lula_visita_Raposa_Serra_do_Sol-2048x1315.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-14281\" class=\"wp-caption-text\">El presidente Lula da Silva visita Raposa-Serra do Sol.<\/figcaption><\/figure>\n<p><span style=\"font-weight: 400;\">Como este proceso lo llevaron a cabo organismos federales, el gobierno del estado de Roraima, alentado por terratenientes locales reacios a ceder el control de estas tierras, intent\u00f3 detener la demarcaci\u00f3n de Raposa-Serra do Sol. El Gobierno estatal present\u00f3 un <a href=\"https:\/\/www.cidh.oas.org\/annualrep\/2010eng\/BRAD250-04EN.DOC\" class=\"broken_link\">requerimiento judicial<\/a> alegando que \u00abla FUNAI ha promovido la indemnizaci\u00f3n y el traslado de los colonos no ind\u00edgenas desde 2002\u00bb. El requerimiento articula el proceso de desalojo, y la posterior indemnizaci\u00f3n de los \u00abasentados no ind\u00edgenas\u00bb, y c\u00f3mo \u00abun grupo de 40 a 50 familias, bajo el liderazgo de 8 propietarios de empresas de cultivo de arroz a gran escala, no aceptan las ofertas del gobierno y se niegan a abandonar el lugar.\u00bb La medida cautelar significaba que los colonos no podr\u00edan ser desalojados hasta que se resolvieran las acciones legales relativas a la demarcaci\u00f3n de Raposa-Serra do Sol, lo que requer\u00eda la intervenci\u00f3n del Tribunal Supremo de Brasil, que inicialmente fij\u00f3 el 27 de agosto de 2008 como fecha de su fallo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El primer y \u00fanico juez que vot\u00f3 el 27 de agosto, Carlos Ayres Britto, <a href=\"https:\/\/www.reuters.com\/article\/us-brazil-indians-idUSN2750535120080827\">vot\u00f3 a favor<\/a> de la demarcaci\u00f3n, afirmando que los pueblos ind\u00edgenas de Raposa-Serra do Sol son los <a href=\"https:\/\/www.survivalinternational.org\/news\/3662\">ocupantes originales y continuos del territorio<\/a>, y que era necesario mantener el \u00e1rea de tierra delineada por la FUNAI para garantizar que estas comunidades pudieran mantener su forma de vida. La sentencia se aplaz\u00f3 despu\u00e9s de que uno de los magistrados, Carlos Alberto Menezes Direito, pidiera m\u00e1s tiempo para seguir examinando el caso. La segunda sesi\u00f3n de la sentencia tuvo lugar el 10 de diciembre, con otros <a href=\"https:\/\/www.survivalinternational.org\/news\/4021\">siete magistrados<\/a> votando a favor de Raposa-Serra do Sol, hasta que el ministro Marco Aur\u00e9lio de Mello solicit\u00f3 revisar m\u00e1s a fondo el caso. Finalmente, el 19 de marzo de 2009, el Tribunal Supremo confirm\u00f3 la validez de Raposa-Serra do Sol, con el voto a favor de 10 jueces y el <a href=\"https:\/\/cimi.org.br\/2009\/03\/28480\/\">\u00fanico voto en contra por parte del Ministro de Mello.<\/a><\/span><\/p>\n<figure id=\"attachment_14284\" aria-describedby=\"caption-attachment-14284\" style=\"width: 1597px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-14284\" src=\"https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/1597px-Julgamento_de_demarcaC3A7C3A3o_contC3ADnua_da_Terra_IndC3ADgena_Raposa_Serra_do_Sol2C_19-03-2009_01.jpg\" alt=\"\" width=\"1597\" height=\"1198\" srcset=\"https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/1597px-Julgamento_de_demarcaC3A7C3A3o_contC3ADnua_da_Terra_IndC3ADgena_Raposa_Serra_do_Sol2C_19-03-2009_01.jpg 1597w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/1597px-Julgamento_de_demarcaC3A7C3A3o_contC3ADnua_da_Terra_IndC3ADgena_Raposa_Serra_do_Sol2C_19-03-2009_01-600x450.jpg 600w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/1597px-Julgamento_de_demarcaC3A7C3A3o_contC3ADnua_da_Terra_IndC3ADgena_Raposa_Serra_do_Sol2C_19-03-2009_01-300x225.jpg 300w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/1597px-Julgamento_de_demarcaC3A7C3A3o_contC3ADnua_da_Terra_IndC3ADgena_Raposa_Serra_do_Sol2C_19-03-2009_01-1024x768.jpg 1024w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/1597px-Julgamento_de_demarcaC3A7C3A3o_contC3ADnua_da_Terra_IndC3ADgena_Raposa_Serra_do_Sol2C_19-03-2009_01-768x576.jpg 768w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/1597px-Julgamento_de_demarcaC3A7C3A3o_contC3ADnua_da_Terra_IndC3ADgena_Raposa_Serra_do_Sol2C_19-03-2009_01-1536x1152.jpg 1536w\" sizes=\"(max-width: 1597px) 100vw, 1597px\" \/><figcaption id=\"caption-attachment-14284\" class=\"wp-caption-text\">Una comunidad de Raposa-Serra do Sol ve la retransmisi\u00f3n del juicio.<\/figcaption><\/figure>\n<p><span style=\"font-weight: 400;\">La <a href=\"https:\/\/redir.stf.jus.br\/paginadorpub\/paginador.jsp?docTP=AC&amp;docID=630133)%20was%20given%20with%2019%20conditions%20(https:\/\/www.conjur.com.br\/2009-mar%E2%80%9319\/supremo-fixa-diretrizes-demarcacao-terras-indigenas?pagina=2\">sentencia<\/a> se dict\u00f3 con 19 condiciones, denominadas <a href=\"https:\/\/apiboficial.org\/marco-temporal),%20which%20gave%20Brazilian%20states%20the%20right%20to%20be%20involved%20in%20demarcation%20processes,%20and%20could%20effect%20(http:\/verbetes.cetem.gov.br\/verbetes\/ExibeVerbete.aspx?verid=195\" class=\"broken_link\">\u00abgarant\u00edas institucionales\u00bb<\/a>, que otorgaban a los Estados brasile\u00f1os el derecho a participar en los procesos de demarcaci\u00f3n y pod\u00edan <a href=\"http:\/\/verbetes.cetem.gov.br\/verbetes\/ExibeVerbete.aspx?verid=195\" class=\"broken_link\">afectar a la forma<\/a> en que se aprobaran los territorios ind\u00edgenas en el futuro. Entre las 19 condiciones de la sentencia Raposa-Serra do Sol se encontraba la primera <a href=\"https:\/\/apiboficial.org\/marco-temporal\">articulaci\u00f3n legal<\/a> del <a href=\"https:\/\/pt.wikipedia.org\/wiki\/Marco_temporal_das_terras_ind%C3%ADgenas\">Marco Temporal.<\/a><\/span><\/p>\n<p><span style=\"font-weight: 400;\">El debate sobre el Marco Temporal se relaciona con los derechos ind\u00edgenas a la tierra, a los que se hace referencia en la Constituci\u00f3n, y espec\u00edficamente a la tierra que \u00abocupan tradicionalmente\u00bb. A lo largo del caso hubo un debate significativo sobre la conexi\u00f3n atemporal entre los pueblos ind\u00edgenas y la tierra que define su ser, y c\u00f3mo la tierra y los pueblos ind\u00edgenas est\u00e1n interconectados. Sin embargo, como el caso surgi\u00f3 de las tensiones entre las distintas percepciones del territorio en disputa -de los pueblos ind\u00edgenas, los productores de arroz, los agricultores y los mineros, as\u00ed como de los gobiernos estatal y federal-, fue necesaria una articulaci\u00f3n espec\u00edfica de los derechos de los pueblos ind\u00edgenas y de las leyes que los defienden. En aras de la especificidad, citamos la <a href=\"https:\/\/redir.stf.jus.br\/paginadorpub\/paginador.jsp?docTP=AC&amp;docID=630133\">sentencia<\/a> (aunque se trata de una traducci\u00f3n de la misma) y las palabras del Ministro Carlos Alberto Menezes Direito:<\/span><\/p>\n<p style=\"padding-left: 40px;\"><span style=\"font-weight: 400;\">\u00abEn primer lugar, las tierras ind\u00edgenas son tierras ocupadas por indios. No son tierras que ocuparon en tiempos pasados y ya no ocupan; no son tierras que ocuparon hasta cierta fecha y ya no ocupan. Son tierras ocupadas por los indios cuando se promulg\u00f3 la Constituci\u00f3n de 1988.<\/span><\/p>\n<p style=\"padding-left: 40px;\"><span style=\"font-weight: 400;\">\u00abEl hito para determinar la ocupaci\u00f3n ind\u00edgena (5\/10\/1988) deriva del propio sistema constitucional de protecci\u00f3n de los derechos de los indios, que no pod\u00eda dejar de abarcar todas las tierras ind\u00edgenas existentes cuando se promulg\u00f3 la Constituci\u00f3n, so pena de dar lugar al despojo ileg\u00edtimo de indios por no indios despu\u00e9s de su entrada en vigor. Esto ocurri\u00f3 incluso despu\u00e9s de la Constituci\u00f3n de 1946, a pesar de que garantizaba su derecho sobre sus tierras&#8230; La correcta extensi\u00f3n de la protecci\u00f3n iniciada por la Constituci\u00f3n de 1988 requiere, por lo tanto, que se verifique la presencia de indios en la fecha de su promulgaci\u00f3n&#8230; La ocupaci\u00f3n es, por lo tanto, un hecho a ser verificado.<\/span><\/p>\n<p style=\"padding-left: 40px;\"><span style=\"font-weight: 400;\">\u00abEn segundo lugar, las tierras ind\u00edgenas son tierras tradicionalmente ocupadas por indios. Para Jos\u00e9 Afonso da Silva, tantas veces citado en este proceso, contrariamente a lo que prevalec\u00eda en Constituciones anteriores, el adverbio &#8216;tradicionalmente&#8217; no debe entenderse como referido a una ocupaci\u00f3n desde tiempos m\u00e1s que prehist\u00f3ricos, una ocupaci\u00f3n inmemorial:<\/span><\/p>\n<p style=\"padding-left: 40px;\"><span style=\"font-weight: 400;\">\u00abLa expresi\u00f3n &#8216;Tierras tradicionalmente ocupadas&#8217; no revela una relaci\u00f3n temporal. Si nos remitimos a la Carta de 1 de abril de 1680, en la que se reconoc\u00eda que los indios ten\u00edan las tierras donde se encontraban al igual que las tierras que ocupaban en el interior, veremos que la expresi\u00f3n tradicionalmente ocupadas no significa ocupaci\u00f3n inmemorial. No significa, por lo tanto, tierras ocupadas inmemorialmente, es decir, tierras que habr\u00edan estado ocupando desde tiempos remotos que ya se han perdido en la memoria y, por lo tanto, s\u00f3lo \u00e9stas ser\u00edan sus tierras\u00bb.\u00a0<\/span><\/p>\n<p style=\"padding-left: 40px;\"><span style=\"font-weight: 400;\">\u00abEl concepto indica el modo de ocupaci\u00f3n, la forma en que los indios se relacionan con la tierra. Es un \u00e1ngulo nuevo respecto a las Constituciones anteriores que, si por un lado justifica la extensi\u00f3n geogr\u00e1fica de los derechos a reconocer, por otro puede significar la exigencia de que la ocupaci\u00f3n por los indios sea conforme a la cultura y al &#8216;modus vivendi&#8217; que se desea preservar&#8230;\u00bb.<\/span><\/p>\n<p style=\"padding-left: 40px;\"><span style=\"font-weight: 400;\">\u00ab&#8216;Tierras que los indios ocupan tradicionalmente&#8217; son, por supuesto, tierras que los indios han ocupado durante alg\u00fan tiempo al momento de la promulgaci\u00f3n de la Constituci\u00f3n. Se trata tanto de una presencia constante como de la persistencia en estas tierras. Las tierras que eventualmente son abandonadas no se prestan a la clasificaci\u00f3n como tierras ind\u00edgenas, como ya se dijo en el Precedente n\u00ba 650 de este Supremo Tribunal Federal. Una presencia bien definida en el espacio durante un cierto per\u00edodo de tiempo y una persistencia de esa presencia, que hace de la habitaci\u00f3n permanente otro hecho a ser verificado&#8230;<\/span><\/p>\n<p style=\"padding-left: 40px;\"><span style=\"font-weight: 400;\">\u00abPropongo, por lo tanto, que adoptemos como criterio constitucional no la teor\u00eda del indigenato, sino la del hecho ind\u00edgena. La apreciaci\u00f3n del hecho ind\u00edgena el 5 de octubre de 1988 supone una opci\u00f3n que prestigia la seguridad jur\u00eddica y evita las dificultades pr\u00e1cticas de una investigaci\u00f3n inmemorial de la ocupaci\u00f3n ind\u00edgena. Pero la vivienda permanente no es el \u00fanico par\u00e1metro a utilizar en la identificaci\u00f3n de las tierras ind\u00edgenas. En verdad, es el par\u00e1metro para identificar la base o n\u00facleo de ocupaci\u00f3n de las tierras ind\u00edgenas, a partir del cual deben manifestarse las dem\u00e1s expresiones de esa ocupaci\u00f3n.\u00bb<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Estas palabras son lo que se conoce como la tesis del Marco Temporal. Se trata de un cambio de la teor\u00eda del indigenato -la <a href=\"https:\/\/sumauma.com\/en\/grito-indigena-julgamento-seculo-sem-demarcacao-nao-ha-democracia\/#:~:text=The%20idea%20that%20%E2%80%9Cthe%20lands,called%20the%20theory%20of%20indigenato\">creencia<\/a> de que los Derechos de los Pueblos Ind\u00edgenas son anteriores a la concepci\u00f3n del Estado brasile\u00f1o- al \u00abhecho ind\u00edgena\u00bb -fijar la fecha de ocupaci\u00f3n a la Constituci\u00f3n-, un intento de crear claridad entre las diferentes percepciones de la demarcaci\u00f3n de los territorios ind\u00edgenas en Brasil. El ministro Gilmar Mendes <a href=\"https:\/\/www.conjur.com.br\/2009-mar%E2%80%9319\/supremo-fixa-diretrizes-demarcacao-terras-indigenas\" class=\"broken_link\">describi\u00f3<\/a> la sentencia y sus condiciones:<\/span><\/p>\n<p style=\"padding-left: 40px;\"><span style=\"font-weight: 400;\">\u00abFijamos un verdadero estatuto que debe aplicarse no s\u00f3lo al caso de Raposa-Serra do Sol, sino tambi\u00e9n a los dem\u00e1s procesos de demarcaci\u00f3n, incluidos los procesos en curso. El tribunal estableci\u00f3, por ejemplo, que las zonas ya demarcadas ya no estar\u00e1n sujetas a revisi\u00f3n, ni despu\u00e9s ni antes de la Constituci\u00f3n. Con esto, ponemos fin a un gran n\u00famero de controversias y a algunos impulsos expansionistas\u00bb.<\/span><\/p>\n<figure id=\"attachment_14258\" aria-describedby=\"caption-attachment-14258\" style=\"width: 856px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-14258\" src=\"https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/856px-Julgamento_de_demarcaC3A7C3A3o_contC3ADnua_da_Terra_IndC3ADgena_Raposa_Serra_do_Sol2C_19-03-2009_Gilmar_Mendes_1.jpg\" alt=\"\" width=\"856\" height=\"1198\" srcset=\"https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/856px-Julgamento_de_demarcaC3A7C3A3o_contC3ADnua_da_Terra_IndC3ADgena_Raposa_Serra_do_Sol2C_19-03-2009_Gilmar_Mendes_1.jpg 856w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/856px-Julgamento_de_demarcaC3A7C3A3o_contC3ADnua_da_Terra_IndC3ADgena_Raposa_Serra_do_Sol2C_19-03-2009_Gilmar_Mendes_1-600x840.jpg 600w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/856px-Julgamento_de_demarcaC3A7C3A3o_contC3ADnua_da_Terra_IndC3ADgena_Raposa_Serra_do_Sol2C_19-03-2009_Gilmar_Mendes_1-214x300.jpg 214w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/856px-Julgamento_de_demarcaC3A7C3A3o_contC3ADnua_da_Terra_IndC3ADgena_Raposa_Serra_do_Sol2C_19-03-2009_Gilmar_Mendes_1-732x1024.jpg 732w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/856px-Julgamento_de_demarcaC3A7C3A3o_contC3ADnua_da_Terra_IndC3ADgena_Raposa_Serra_do_Sol2C_19-03-2009_Gilmar_Mendes_1-768x1075.jpg 768w\" sizes=\"(max-width: 856px) 100vw, 856px\" \/><figcaption id=\"caption-attachment-14258\" class=\"wp-caption-text\">El Ministro Gilmar Mendes durante la sentencia de Raposa-Serra do Sol.<\/figcaption><\/figure>\n<p><span style=\"font-weight: 400;\">La sentencia llev\u00f3 a la demarcaci\u00f3n de Raposa-Serra do Sol y al desalojo de los ocupantes no ind\u00edgenas. Aunque una decisi\u00f3n del Tribunal Supremo no define decisiones futuras, suele utilizarse para enmarcar casos similares, y tras el alivio inicial que supuso la demarcaci\u00f3n definitiva de Raposa-Serra do Sol, surgieron temores sobre c\u00f3mo influir\u00edan las 19 condiciones en los derechos de los pueblos ind\u00edgenas de todo Brasil. En una <a href=\"http:\/\/www.forestpeoples.org\/sites\/default\/files\/publication\/2010\/08\/brazilcerdupdatejan10eng.pdf\">carta<\/a> dirigida al <a href=\"https:\/\/www.ohchr.org\/en\/treaty-bodies\/cerd#:~:text=The%20Committee%20on%20the%20Elimination,full%20realization%20of%20human%20rights\" class=\"broken_link\">Comit\u00e9 de las Naciones Unidas para la Eliminaci\u00f3n de la Discriminaci\u00f3n Racial<\/a>, los pueblos de Raposa-Serra do Sol, junto con el Consejo Ind\u00edgena de Roraima, expresaron su \u00abpreocupaci\u00f3n\u00bb por la sentencia del Tribunal Supremo:<\/span><\/p>\n<p style=\"padding-left: 40px;\"><span style=\"font-weight: 400;\">\u00abEl Tribunal Supremo no se limit\u00f3 a refrendar la demarcaci\u00f3n de Raposa, sino que fue m\u00e1s all\u00e1 al interpretar y definir -si no &#8216;redefinir&#8217;- los derechos de los pueblos ind\u00edgenas tal y como se afirman actualmente en el art\u00edculo 231 de la Constituci\u00f3n federal brasile\u00f1a. Entre otras cosas, el Tribunal Supremo impuso numerosas limitaciones a los derechos de los pueblos ind\u00edgenas sobre su propiedad. En muchos sentidos, esos derechos son ahora irreconocibles si se comparan con su creciente significado y aplicaci\u00f3n en la legislaci\u00f3n brasile\u00f1a\u00bb.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En el <a href=\"https:\/\/digitallibrary.un.org\/record\/663918\/files\/A_HRC_12_34_Add%E2%80%932-EN.pdf?ln=en\">\u00abInforme Especial sobre la Situaci\u00f3n de los Derechos Humanos de los Pueblos Ind\u00edgenas en Brasil\u00bb<\/a>, <a href=\"https:\/\/en.wikipedia.org\/wiki\/James_Anaya\">James Anaya<\/a>, Relator Especial sobre los Derechos de los Pueblos Ind\u00edgenas, ofreci\u00f3 la perspectiva de la ONU sobre la situaci\u00f3n:<\/span><\/p>\n<p style=\"padding-left: 40px;\"><span style=\"font-weight: 400;\">\u00abEl art\u00edculo 27 de la Declaraci\u00f3n de las Naciones Unidas afirma el derecho de los pueblos ind\u00edgenas a &#8216;poseer, utilizar, desarrollar y controlar las tierras, territorios y recursos&#8217; que tradicionalmente ocupan; por su parte, el Convenio 169 de la OIT declara en su art\u00edculo 14, &#8216;Deber\u00e1n reconocerse a los pueblos interesados los derechos de propiedad y de posesi\u00f3n sobre las tierras que tradicionalmente ocupan.&#8217; A la luz de estas normas internacionales a las que Brasil se ha comprometido, los pueblos ind\u00edgenas deber\u00e1n gozar efectivamente de derechos sobre sus tierras que sean equivalentes a la propiedad, y el inter\u00e9s de propiedad del Estado sobre las tierras ind\u00edgenas deber\u00e1 operar s\u00f3lo como un medio de protecci\u00f3n y no como un medio de interferencia con el control ind\u00edgena. Adem\u00e1s, tanto en virtud de la Declaraci\u00f3n (arts. 19, 30, 32) como del Convenio 169 de la OIT (arts. 6, 15.2), los pueblos ind\u00edgenas tienen derecho a ser consultados sobre cualquier decisi\u00f3n que les afecte con el objetivo de lograr su acuerdo o consentimiento, incluso en relaci\u00f3n con la explotaci\u00f3n de recursos del subsuelo propiedad del Estado o el establecimiento de instalaciones militares. Cualquiera que sea la validez o la disposici\u00f3n final de las 19 condiciones articuladas por el Supremo Tribunal Federal, las autoridades administrativas, legislativas y militares deben ejercer sus poderes en relaci\u00f3n con las tierras ind\u00edgenas de forma coherente con estas normas internacionales. Adem\u00e1s, es deseable la promulgaci\u00f3n de legislaci\u00f3n nacional o reglamentos administrativos para aplicar estas normas.\u00bb<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En este periodo se reaviv\u00f3 el debate sobre la <a href=\"https:\/\/en.wikipedia.org\/wiki\/Belo_Monte_Dam\">central hidroel\u00e9ctrica de Belo Monte.<\/a> Inicialmente propuesta en la d\u00e9cada de 1970, la central iba a construirse en el estado de Par\u00e1, en el r\u00edo Xingu, y tras m\u00e1s de 40 a\u00f1os de mapeos y una considerable resistencia de los pueblos ind\u00edgenas y las ONG, un consorcio de 18 miembros llamado Norte Energia -integrado por la empresa estatal Eletrobr\u00e1s y un pu\u00f1ado de fondos de pensiones estatales y de inversi\u00f3n privada- gan\u00f3 una subasta en 2010 para iniciar la construcci\u00f3n. El Tribunal Federal <a href=\"https:\/\/noticias.uol.com.br\/cotidiano\/ultimas-noticias\/2010\/04\/14\/justica-suspende-leilao-e-licenca-de-belo-monte.htm\" class=\"broken_link\">suspendi\u00f3<\/a> la licencia por \u00abda\u00f1os irreparables\u00bb al medio ambiente y por considerar que el proyecto era inconstitucional, concretamente en relaci\u00f3n con el art\u00edculo 176 de la Constituci\u00f3n Federal y con el hecho de que la represa propuesta se construir\u00eda en territorios ind\u00edgenas. Las discusiones se sucedieron entre el Instituto Brasile\u00f1o de Medio Ambiente y Recursos Naturales Renovables (IBAMA), la FUNAI, los \u00f3rganos representativos de las numerosas comunidades ind\u00edgenas afectadas y el Gobierno brasile\u00f1o, hasta que el presidente Lula da Silva firm\u00f3 un contrato con Norte Energia el 26 de agosto de 2010. El Gobierno brasile\u00f1o cre\u00eda que el proyecto mantendr\u00eda el crecimiento econ\u00f3mico y <a href=\"https:\/\/web.archive.org\/web\/20121102034645\/http:\/\/www.businessweek.com\/ap\/financialnews\/D9NJBCFO0.htm\">sacar\u00eda a una parte de la poblaci\u00f3n de la pobreza<\/a>, lo que se relaciona con el art\u00edculo 231 de la Constituci\u00f3n y la capacidad del Gobierno brasile\u00f1o de poseer territorio ind\u00edgena si se hace con \u00abinter\u00e9s p\u00fablico relevante\u00bb.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Un tribunal federal de Par\u00e1 suspendi\u00f3 el inicio de las obras por <a href=\"https:\/\/www.theguardian.com\/world\/2011\/feb\/26\/brazil-belo-monte-dam-ruling\">no cumplirse<\/a> los requisitos medioambientales del proyecto. Esta decisi\u00f3n fue <a href=\"https:\/\/amazonwatch.org\/news\/2011\/0305-regional-judge-overturns-ban-on-construction-of-controversial-belo-monte-dam\">revocada<\/a> por Olindo Menezes, Presidente del Tribunal Regional Federal de Brasilia, un tribunal superior al de Par\u00e1. Finalmente se <a href=\"https:\/\/www.theguardian.com\/environment\/2011\/mar\/10\/belo-monte-hydroelectric-work\">iniciaron las obras<\/a>, pero se suspendieron r\u00e1pidamente por <a href=\"https:\/\/www.bbc.com\/news\/world-latin-america%E2%80%9315102520\" class=\"broken_link\">decisi\u00f3n<\/a> de otro juez, <a href=\"https:\/\/www.bbc.com\/news\/world-latin-america%E2%80%9319404740\" class=\"broken_link\">revocada por el Tribunal Supremo.<\/a> La construcci\u00f3n de Belo Monte afect\u00f3 directamente a los pueblos Arara, Arawat\u00e9, Assurini, Curuaya, Juruna, Kayap\u00f3, Parakan\u00e3, Xicrin y Xipaya. Para los pueblos Arara y Juruna de la Volta Grande do Xingu, los impactos fueron enormes, con casi el 80% del r\u00edo Xingu desviado en sus tierras, transformando completamente su territorio y afectando simult\u00e1neamente a su econom\u00eda, pol\u00edtica y cultura.<\/span><\/p>\n<figure id=\"attachment_14260\" aria-describedby=\"caption-attachment-14260\" style=\"width: 1600px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-14260\" src=\"https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/1600px-UHE_Belo_Monte_rio_Xingu.jpg\" alt=\"\" width=\"1600\" height=\"1016\" srcset=\"https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/1600px-UHE_Belo_Monte_rio_Xingu.jpg 1600w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/1600px-UHE_Belo_Monte_rio_Xingu-600x381.jpg 600w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/1600px-UHE_Belo_Monte_rio_Xingu-300x191.jpg 300w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/1600px-UHE_Belo_Monte_rio_Xingu-1024x650.jpg 1024w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/1600px-UHE_Belo_Monte_rio_Xingu-768x488.jpg 768w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/1600px-UHE_Belo_Monte_rio_Xingu-1536x975.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><figcaption id=\"caption-attachment-14260\" class=\"wp-caption-text\">La central hidroel\u00e9ctrica de Belo Monte.<\/figcaption><\/figure>\n<p><span style=\"font-weight: 400;\">Mientras tanto, continuaba el debate sobre el Marco Temporal. Se presentaron <a href=\"https:\/\/memoria.ebc.com.br\/agenciabrasil\/noticia\/2012%E2%80%9307%E2%80%9320\/condicoes-do-stf-sobre-raposa-serra-do-sol-sao-alvo-de-questionamentos-que-atingem-portaria-da-agu\" class=\"broken_link\">seis solicitudes<\/a> de clarificaci\u00f3n de las decisiones Raposa-Serra do Sol, lo que llev\u00f3 al Procurador General de Brasil, mediante la Ordenanza 303, a declarar que las condiciones eran obligatorias para todos los procesos de demarcaci\u00f3n de territorios ind\u00edgenas. Se produjeron <a href=\"https:\/\/g1.globo.com\/distrito-federal\/noticia\/2012\/11\/indios-protestam-ao-lado-do-palacio-do-planalto-contra-portaria-da-agu.html\">protestas en todo Brasil<\/a> y la Comisi\u00f3n Nacional de Pol\u00edtica Ind\u00edgena (CNPI) pidi\u00f3 al Gobierno brasile\u00f1o que revocara la <a href=\"https:\/\/memoria.ebc.com.br\/2012\/08\/comissao-de-politica-indigenista-pede-revogacao-de-portaria-contraria-a-ampliacao-de-terras\" class=\"broken_link\">Ordenanza<\/a> del Fiscal General. Esto dio lugar a <a href=\"https:\/\/memoria.ebc.com.br\/2012\/08\/comissao-de-politica-indigenista-pede-revogacao-de-portaria-contraria-a-ampliacao-de-terras\" class=\"broken_link\">otro juicio<\/a> ante el Tribunal Supremo, en el que los magistrados <a href=\"https:\/\/apiboficial.org\/marco-temporal\">resolvieron<\/a> que las sentencias Raposa-Serra do Sol \u00abno son vinculantes para los jueces y tribunales a la hora de examinar otros casos relacionados con diferentes tierras ind\u00edgenas\u00bb y que la sentencia Raposa-Serra do Sol \u00abs\u00f3lo se aplica a la tierra en cuesti\u00f3n\u00bb. A pesar de esta decisi\u00f3n, el Fiscal General <a href=\"https:\/\/g1.globo.com\/brasil\/noticia\/2013\/10\/regra-da-raposa-serra-do-sol-nao-vale-para-todas-terras-decide-stf.html\">volvi\u00f3 a publicar<\/a> la Ordenanza 303. El caso Raposa-Serra do Sol fue entonces referenciado en sentencias sobre los territorios de <a href=\"https:\/\/site-antigo.socioambiental.org\/pt-br\/noticias-socioambientais\/decisoes-recentes-ameacam-direitos-territoriais-indigenas-e-abrem-polemica-no-stf\" class=\"broken_link\">Guyrarok\u00e1<\/a>, <a href=\"https:\/\/site-antigo.socioambiental.org\/pt-br\/noticias-socioambientais\/decisao-do-stf-reforca-ataque-aos-direitos-territoriais-indigenas\" class=\"broken_link\">Lim\u00e3o Verde<\/a> y <a href=\"https:\/\/apublica.org\/2016\/09\/adeus-guyraroka\/\">Porquinhos<\/a>, que fueron suspendidas o anuladas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Estas sentencias, junto con la tensi\u00f3n de las posiciones contrapuestas del Fiscal General y del Tribunal Supremo, crearon una mayor ambig\u00fcedad en la demarcaci\u00f3n de los territorios ind\u00edgenas, lo que inspir\u00f3 al Gobierno del presidente Michel Temer, en julio de 2017, a publicar una <a href=\"https:\/\/conjur.com.br\/2017-jul%E2%80%9320\/decisao-raposa-serra-sol-vale-toda-administracao\" class=\"broken_link\">opini\u00f3n oficial<\/a> sobre el asunto, haciendo hincapi\u00e9 en la tesis Marco Temporal, que Temer consider\u00f3 como<a href=\"https:\/\/www1.folha.uol.com.br\/poder\/2017\/07\/1902688-temer-assina-parecer-que-pode-parar-demarcacao-de-terras-indigenas.shtml\"> \u00abvinculante\u00bb.<\/a> La fiscal general de la \u00e9poca, Grace Mendon\u00e7a, ofreci\u00f3 su <a href=\"https:\/\/amazonasatual.com.br\/decisao-do-stf-sobre-raposa-serra-do-sol-vai-balizar-demarcacoes\/\" class=\"broken_link\">perspectiva:<\/a><\/span><\/p>\n<p style=\"padding-left: 40px;\"><span style=\"font-weight: 400;\">\u00abEsta opini\u00f3n, ahora vinculante para la administraci\u00f3n p\u00fablica federal, rinde homenaje a las directrices establecidas por el STF en el proceso de demarcaci\u00f3n Raposa-Serra do Sol, proporciona una mayor seguridad jur\u00eddica y se alinea con un esfuerzo de la AGU para promover la reducci\u00f3n de litigios\u00bb.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La FUNAI <a href=\"https:\/\/apiboficial.org\/marco-temporal\">reevalu\u00f3<\/a> inmediatamente los procesos de demarcaci\u00f3n de territorios ind\u00edgenas en todo Brasil, incluidos los ya presentados al Ministerio de Justicia para su aprobaci\u00f3n. A esto le sigui\u00f3 la elecci\u00f3n de Jair Bolsonaro como presidente, que cumpli\u00f3 su promesa electoral de <a href=\"https:\/\/news.mongabay.com\/2022\/10\/activists-slam-bolsonaro-rule-change-seen-as-ending-demarcation-of-indigenous-lands\/\">no demarcar ning\u00fan nuevo territorio ind\u00edgena<\/a>. Bolsonaro, defensor del agronegocio y la miner\u00eda, aplic\u00f3 activamente pol\u00edticas que amenazaban los derechos y la vida de los pueblos ind\u00edgenas, lo que llev\u00f3 al actual presidente Lula da Silva a acusar a su predecesor de <a href=\"https:\/\/www.euronews.com\/green\/2023\/01\/23\/brazil-president-lula-accuses-bolsonaro-of-genocide-after-gold-mining-causes-indigenous-de\" class=\"broken_link\">\u00abgenocidio\u00bb contra las comunidades ind\u00edgenas de Brasil<\/a>, en particular los <a href=\"https:\/\/acervo.socioambiental.org\/sites\/default\/files\/documents\/yal00067_en.pdf\">Yanomami.<\/a><\/span><\/p>\n<p><span style=\"font-weight: 400;\">A pesar de todas estas sentencias y decisiones, el debate en torno al Marco Temporal sigue sin resolverse. Esto se debe a un recurso interpuesto por la FUNAI ante el Tribunal Supremo en 2016 contra la Fundaci\u00f3n de Apoyo Tecnol\u00f3gico al Medio Ambiente (FATMA) de Santa Catarina, que previamente interpuso una <a href=\"https:\/\/www.conjur.com.br\/2019-fev%E2%80%9325\/stf-julgara-posse-areas-tradicionalmente-ocupadas-indigenas\" class=\"broken_link\">acci\u00f3n de recuperaci\u00f3n<\/a> del Territorio Ind\u00edgena Ibirama-Lakl\u00e3n\u00f5 en el Estado de Santa Catarina en <a href=\"https:\/\/sumauma.com\/en\/grito-indigena-julgamento-seculo-sem-demarcacao-nao-ha-democracia\/\">2009<\/a>. Este recurso tuvo una <a href=\"https:\/\/www.conectas.org\/en\/noticias\/in-historic-judgment-supreme-court-could-define-the-course-of-indigenous-land-demarcation-in-brazil\/\">\u00abrepercusi\u00f3n general\u00bb<\/a> reconocida por unanimidad por el Tribunal Supremo el 11 de abril de 2019, lo que significa que la sentencia de este caso -denominado Recurso Extraordinario 1.017.365- actuar\u00e1 como <a href=\"https:\/\/www.conectas.org\/en\/noticias\/time-frame-understand-why-the-case-in-the-supreme-court-can-define-the-future-of-indigenous-lands\/\">precedente<\/a> para todos los casos relacionados con la demarcaci\u00f3n de territorios ind\u00edgenas en todos los niveles del sistema judicial brasile\u00f1o.<\/span><\/p>\n<figure id=\"attachment_14262\" aria-describedby=\"caption-attachment-14262\" style=\"width: 1599px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-14262\" src=\"https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/1599px-Contra_o_marco_temporal_Ato_PolC3ADtico_e_pronunciamento_dos_povos_indC3ADgenas_285217048639529.jpg\" alt=\"\" width=\"1599\" height=\"820\" srcset=\"https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/1599px-Contra_o_marco_temporal_Ato_PolC3ADtico_e_pronunciamento_dos_povos_indC3ADgenas_285217048639529.jpg 1599w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/1599px-Contra_o_marco_temporal_Ato_PolC3ADtico_e_pronunciamento_dos_povos_indC3ADgenas_285217048639529-600x308.jpg 600w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/1599px-Contra_o_marco_temporal_Ato_PolC3ADtico_e_pronunciamento_dos_povos_indC3ADgenas_285217048639529-300x154.jpg 300w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/1599px-Contra_o_marco_temporal_Ato_PolC3ADtico_e_pronunciamento_dos_povos_indC3ADgenas_285217048639529-1024x525.jpg 1024w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/1599px-Contra_o_marco_temporal_Ato_PolC3ADtico_e_pronunciamento_dos_povos_indC3ADgenas_285217048639529-768x394.jpg 768w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/1599px-Contra_o_marco_temporal_Ato_PolC3ADtico_e_pronunciamento_dos_povos_indC3ADgenas_285217048639529-1536x788.jpg 1536w\" sizes=\"(max-width: 1599px) 100vw, 1599px\" \/><figcaption id=\"caption-attachment-14262\" class=\"wp-caption-text\">Protestas contra el Marco Temporal en Brasilia.<\/figcaption><\/figure>\n<p><span style=\"font-weight: 400;\">El desarrollo de este <a href=\"https:\/\/portal.stf.jus.br\/processos\/detalhe.asp?incidente=5109720\" class=\"broken_link\">caso<\/a> y sus continuos retrasos se produjeron paralelamente al avance del <a href=\"https:\/\/www25.senado.leg.br\/web\/atividade\/materias\/-\/materia\/157888\">Proyecto de Ley (PL) 490\/2007<\/a>. El Proyecto de Ley, presentado por el Diputado Federal de Mato Grasso <a href=\"https:\/\/www.camara.leg.br\/deputados\/141448\/biografia\">Homero Pereira<\/a> en 2007, ha recibido desde entonces 13 puntos adicionales y ha sido archivado y desarchivado tres veces. El PL 490 fue <a href=\"https:\/\/www.nationalgeographic.com\/history\/article\/war-on-indigenous-amazon-communities-in-brazil\">aprobado<\/a> el 23 de junio de 2021 por la Comisi\u00f3n de Constituci\u00f3n y Justicia y pas\u00f3 a la C\u00e1mara de Diputados, la c\u00e1mara baja del Congreso Federal. La Articulaci\u00f3n de Pueblos Ind\u00edgenas de Brasil (APIB) redact\u00f3 una <a href=\"https:\/\/apiboficial.org\/files\/2023\/05\/Nota-Te%CC%81cnica-da-APIB-sobre-o-PL%E2%80%93490_2007%E2%80%931.pdf\" class=\"broken_link\">nota t\u00e9cnica<\/a> que resume las intenciones del PL 490:<\/span><\/p>\n<p style=\"padding-left: 40px;\"><span style=\"font-weight: 400;\">\u00abi) transferir la competencia para la demarcaci\u00f3n de las Tierras Ind\u00edgenas del Poder Ejecutivo al Poder Legislativo; ii) transformar en Ley la tesis del hito temporal, con el objetivo de hacer inviable la demarcaci\u00f3n de las Tierras Ind\u00edgenas; iii) permitir la construcci\u00f3n de carreteras, hidroel\u00e9ctricas y otras obras dentro de las Tierras Ind\u00edgenas, sin consulta previa, libre e informada a las comunidades afectadas; iv) mitigar la diferencia entre la posesi\u00f3n tradicional ind\u00edgena de la tierra, tal y como se establece en la Constituci\u00f3n Federal, y la posesi\u00f3n privada de la tierra en virtud del derecho civil, previendo que los agricultores puedan firmar contratos con los ind\u00edgenas para plantar soja, criar ganado e incluso realizar excavaciones ilegales de oro y explotaciones mineras, lo que viola los derechos de los Pueblos Ind\u00edgenas al usufructo exclusivo de las tierras demarcadas y debilita la protecci\u00f3n y demarcaci\u00f3n de las Tierras Ind\u00edgenas v) autorizar a cualquier persona a cuestionar los procedimientos de demarcaci\u00f3n en todas las fases del proceso, incluidas las ya aprobadas, provocando inseguridad jur\u00eddica; vi) reconocer la legitimidad de los t\u00edtulos, posesiones y dominios que tienen lugar sobre \u00e1reas de ocupaci\u00f3n tradicional, como forma de favorecer el acaparamiento de tierras vii) revivir paradigmas dictatoriales en el sistema jur\u00eddico brasile\u00f1o que fueron superados por la Constituci\u00f3n Federal de 1988, como el r\u00e9gimen tutelar y el asimilacionismo, que buscan aculturar a los Pueblos Ind\u00edgenas (dentro de las normas nacionales), neg\u00e1ndoles el Derecho a la Identidad; viii) desconocer e irrespetar la pol\u00edtica ind\u00edgena de no contacto con los Pueblos Ind\u00edgenas en situaci\u00f3n de aislamiento voluntario, flexibiliz\u00e1ndola; ix) reformular conceptos constitucionales fundamentales de la pol\u00edtica ind\u00edgena, como el car\u00e1cter tradicional de la ocupaci\u00f3n, el derecho originario y el usufructo exclusivo. \u00ab<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El proceso pol\u00edtico del PL 490 est\u00e1 conectado con el proceso legislativo del Marco Temporal, ya que ambos buscan cambiar la interpretaci\u00f3n jur\u00eddica de la Constituci\u00f3n, espec\u00edficamente las reglas de demarcaci\u00f3n de los territorios ind\u00edgenas. La reintroducci\u00f3n del proyecto de ley supuso la simultaneidad de procesos centrados en los territorios ind\u00edgenas en los sistemas legislativo y pol\u00edtico de Brasil.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El 9 de septiembre de 2021, el Supremo Tribunal Federal inici\u00f3 el juicio del Recurso Extraordinario 1.017.365. El ministro Edson Fachin, relator del proceso, vot\u00f3 contra Marco Temporal y la definici\u00f3n de la sentencia Raposa-Serra do Sol, y sus condiciones, como precedente para futuras demarcaciones de territorios ind\u00edgenas. Ofreci\u00f3 su <a href=\"https:\/\/www.conjur.com.br\/2021-set%E2%80%9309\/fachin-vota-tese-marco-temporal\" class=\"broken_link\">perspectiva<\/a> al presentar su voto:<\/span><\/p>\n<p style=\"padding-left: 40px;\"><span style=\"font-weight: 400;\">\u00abEs necesario reconocer que la decisi\u00f3n tomada en la Petici\u00f3n n\u00ba 3.388 (caso Raposa-Serra do Sol), lejos de lograr la paz deseada, trajo una verdadera par\u00e1lisis en la demarcaci\u00f3n de las tierras ind\u00edgenas en el pa\u00eds&#8230; con una intensificaci\u00f3n de los conflictos y un empeoramiento significativo en la calidad de vida de los indios en Brasil&#8230; Decir que Raposa-Serra do Sol es un precedente para toda la cuesti\u00f3n ind\u00edgena es hacer inviables otros grupos \u00e9tnicos ind\u00edgenas. Es decir que la soluci\u00f3n dada a los Macuxi es la misma que la dada a los Guarani. Para los Xokleng, ser\u00eda la misma para los Patax\u00f3. S\u00f3lo quien, con todo respeto, llama \u00abindio\u00bb a todo el mundo olvida las m\u00e1s de 270 lenguas que componen la cultura brasile\u00f1a. Y s\u00f3lo quien pacifica las diferentes y distintas etnias puede decir que la soluci\u00f3n debe ser siempre la misma. Quien no ve la diferencia no promueve la igualdad\u00bb.<\/span><\/p>\n<figure id=\"attachment_14267\" aria-describedby=\"caption-attachment-14267\" style=\"width: 1599px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-14267\" src=\"https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/1599px-TSE_-_Tribunal_Superior_Eleitoral_Ministro_Edson_Fachin_recebe_indC3ADgenas_no_TSE_-_51997705782.jpg\" alt=\"\" width=\"1599\" height=\"1066\" srcset=\"https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/1599px-TSE_-_Tribunal_Superior_Eleitoral_Ministro_Edson_Fachin_recebe_indC3ADgenas_no_TSE_-_51997705782.jpg 1599w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/1599px-TSE_-_Tribunal_Superior_Eleitoral_Ministro_Edson_Fachin_recebe_indC3ADgenas_no_TSE_-_51997705782-600x400.jpg 600w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/1599px-TSE_-_Tribunal_Superior_Eleitoral_Ministro_Edson_Fachin_recebe_indC3ADgenas_no_TSE_-_51997705782-300x200.jpg 300w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/1599px-TSE_-_Tribunal_Superior_Eleitoral_Ministro_Edson_Fachin_recebe_indC3ADgenas_no_TSE_-_51997705782-1024x683.jpg 1024w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/1599px-TSE_-_Tribunal_Superior_Eleitoral_Ministro_Edson_Fachin_recebe_indC3ADgenas_no_TSE_-_51997705782-768x512.jpg 768w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/1599px-TSE_-_Tribunal_Superior_Eleitoral_Ministro_Edson_Fachin_recebe_indC3ADgenas_no_TSE_-_51997705782-1536x1024.jpg 1536w\" sizes=\"(max-width: 1599px) 100vw, 1599px\" \/><figcaption id=\"caption-attachment-14267\" class=\"wp-caption-text\">El ministro Edson Fachin se re\u00fane con l\u00edderes ind\u00edgenas.<\/figcaption><\/figure>\n<p><span style=\"font-weight: 400;\">El caso se aplaz\u00f3 durante una semana, reanud\u00e1ndose el 15 de septiembre de 2021. Esa ma\u00f1ana, el presidente Jair Bolsonaro ofreci\u00f3 sus <a href=\"https:\/\/www.conjur.com.br\/2021-set%E2%80%9315\/alexandre-vista-stf-adia-julgamento-marco-temporal\" class=\"broken_link\">pensamientos<\/a>, \u00absi este nuevo plazo llega a existir, si el Tribunal Supremo as\u00ed lo decide, ser\u00e1 un duro golpe para nuestra agroindustria, con repercusiones internas casi catastr\u00f3ficas, pero tambi\u00e9n en el extranjero.\u00bb Horas despu\u00e9s, el ministro Nunes Marques <a href=\"https:\/\/www.jota.info\/stf\/do-supremo\/moraes-pede-vista-e-suspende-julgamento-sobre-tese-do-marco-temporal%E2%80%9315092021\" class=\"broken_link\">vot\u00f3 a favor<\/a> de Marco Temporal:<\/span><\/p>\n<p style=\"padding-left: 40px;\"><span style=\"font-weight: 400;\">\u00abEs necesario tener en cuenta que la redacci\u00f3n del texto constitucional apunta claramente en la direcci\u00f3n de que la posesi\u00f3n ind\u00edgena debe existir en el a\u00f1o 1988, con car\u00e1cter tradicional. Posesiones posteriores a 1988 no pueden ser consideradas tradicionales porque esto implicar\u00eda no s\u00f3lo el reconocimiento de los derechos ind\u00edgenas a sus tierras, sino tambi\u00e9n el derecho a la expansi\u00f3n ilimitada a nuevas \u00e1reas ya definitivamente incorporadas al mercado inmobiliario nacional.\u00bb<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En su opini\u00f3n, la sentencia Raposa-Serra do Sol y sus condiciones aportan una claridad necesaria que deber\u00eda ayudar a resolver futuras demarcaciones. El ministro Alexandre de Moraes fue el siguiente en votar y pidi\u00f3 ver las actas del caso, retrasando una vez m\u00e1s el proceso.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En abril de este a\u00f1o, la magistrada del Tribunal Supremo Rosa Weber <a href=\"https:\/\/sumauma.com\/en\/grito-indigena-julgamento-seculo-sem-demarcacao-nao-ha-democracia\/\">anunci\u00f3<\/a> que la votaci\u00f3n se reanudar\u00eda el 7 de junio. La decisi\u00f3n de la C\u00e1mara de Diputados sobre el PL 490 tambi\u00e9n se retras\u00f3, aprob\u00e1ndose finalmente el 24 de mayo, lo que llev\u00f3 a una votaci\u00f3n en el Congreso Federal el 30 de mayo, <a href=\"https:\/\/edition.cnn.com\/2023\/05\/30\/americas\/brazil-indigenous-protest-bill-intl-latam\/index.html\">aprob\u00e1ndose<\/a> el proyecto por 283 votos a favor y 155 en contra. El Proyecto de Ley entra as\u00ed en el Senado, donde se le ha dado un nuevo n\u00famero, pasando a denominarse PL 2903. El 7 de junio, en el Tribunal Supremo, el juez Alexandre de Moraes vot\u00f3 en contra de la tesis del Marco Temporal, antes de que el proceso fuera de nuevo interrumpido, esta vez por el juez Andr\u00e9 Mendon\u00e7a, que solicit\u00f3 m\u00e1s tiempo para analizar el caso.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al emitir su voto, el juez Alexandre de Moraes propuso enfoques alternativos a los conflictos causados por futuras demarcaciones. La <a href=\"https:\/\/amazonwatch.org\/news\/2023\/0608-brazils-pivotal-indigenous-land-rights-ruling-faces-another-delay\">primera sugerencia<\/a> se refiere a lo que denomin\u00f3 <a href=\"https:\/\/sumauma.com\/en\/marco-temporal-voto-de-xandao-e-ruim-afirmam-advogados-dos-indigenas\/\">\u00abindemnizaci\u00f3n previa\u00bb<\/a>, por la que el gobierno brasile\u00f1o indemnizar\u00eda a los propietarios de tierras tradicionalmente ocupadas por pueblos ind\u00edgenas -s\u00f3lo si no hay pruebas de apropiaci\u00f3n ilegal de tierras, conflicto f\u00edsico o disputas legales- en la fecha en que se promulg\u00f3 la Constituci\u00f3n. La segunda se refiere a la <a href=\"https:\/\/sumauma.com\/en\/marco-temporal-voto-de-xandao-e-ruim-afirmam-advogados-dos-indigenas\/\">compensaci\u00f3n de territorios confiscados \u00abpor inter\u00e9s p\u00fablico\u00bb<\/a>, en la que el gobierno brasile\u00f1o ofrecer\u00eda a los pueblos ind\u00edgenas un territorio alternativo al que pretend\u00edan demarcar. Mauricio Terena, coordinador jur\u00eddico de APIB, <a href=\"https:\/\/sumauma.com\/en\/marco-temporal-voto-de-xandao-e-ruim-afirmam-advogados-dos-indigenas\/\">cree<\/a> que esta propuesta no apoya a los pueblos ind\u00edgenas, los desconecta de su territorio y puede exacerbar los conflictos actuales.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En respuesta a la crisis creada por las votaciones simult\u00e1neas en el Senado y el Tribunal Supremo, el Relator Especial de la ONU sobre los Derechos de los Pueblos Ind\u00edgenas, Jos\u00e9 Francisco Cal\u00ed Tzay, emiti\u00f3 una declaraci\u00f3n condenando la tesis de Marco Temporal e instando al Tribunal Supremo y al Senado Federal, as\u00ed como al Gobierno brasile\u00f1o, a <a href=\"https:\/\/apiboficial.org\/2023\/06\/14\/relator-da-onu-manifesta-preocupacao-e-recomenda-rejeicao-ao-marco-temporal-no-senado-e-no-stf\/\">\u00abgarantizar reparaciones hist\u00f3ricas para los Pueblos Ind\u00edgenas y evitar la perpetuaci\u00f3n de nuevas injusticias.\u00bb<\/a><\/span><\/p>\n<figure id=\"attachment_14264\" aria-describedby=\"caption-attachment-14264\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-14264\" src=\"https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/800px-Ato_Cultural_contra_o_Marco_Temporal2C_Teatro_Municipal_07.06.23_285295742511729.jpg\" alt=\"\" width=\"800\" height=\"1200\" srcset=\"https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/800px-Ato_Cultural_contra_o_Marco_Temporal2C_Teatro_Municipal_07.06.23_285295742511729.jpg 800w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/800px-Ato_Cultural_contra_o_Marco_Temporal2C_Teatro_Municipal_07.06.23_285295742511729-600x900.jpg 600w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/800px-Ato_Cultural_contra_o_Marco_Temporal2C_Teatro_Municipal_07.06.23_285295742511729-200x300.jpg 200w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/800px-Ato_Cultural_contra_o_Marco_Temporal2C_Teatro_Municipal_07.06.23_285295742511729-683x1024.jpg 683w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/800px-Ato_Cultural_contra_o_Marco_Temporal2C_Teatro_Municipal_07.06.23_285295742511729-768x1152.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-14264\" class=\"wp-caption-text\">Protestas contra Marco Temporal en S\u00e3o Paulo.<\/figcaption><\/figure>\n<p><span style=\"font-weight: 400;\">Es aqu\u00ed donde se encuentra actualmente la situaci\u00f3n en torno a Marco Temporal. Este ha sido un largo proceso en el que se han perdido vidas y a\u00fan m\u00e1s se han visto amenazadas. Ha provocado devastaci\u00f3n a nivel personal, cultural y medioambiental.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Aunque este art\u00edculo se ha centrado en gran medida en las fechas, los proyectos de ley y las sentencias, esto refleja la realidad de la situaci\u00f3n, en la que la vida de las personas y las comunidades, y el entorno natural que nutren y protegen -que sustenta la totalidad de la vida en nuestro planeta- se ha reducido a una fecha concreta y a los argumentos pol\u00edticos y jur\u00eddicos que la sustentan.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Esta es una historia de soberan\u00eda, un concepto que se remonta a 1648 y a la conclusi\u00f3n de la <a href=\"https:\/\/en.wikipedia.org\/wiki\/Thirty_Years%27_War\">Guerra de los Treinta A\u00f1os<\/a> en Europa, y a dos tratados conocidos colectivamente como la <a href=\"https:\/\/en.wikipedia.org\/wiki\/Peace_of_Westphalia\">Paz de Westfalia<\/a>. Estos tratados dieron origen al principio definitorio del sistema internacional de Estados naci\u00f3n, seg\u00fan el cual cada Estado tiene dominio exclusivo sobre su territorio determinado. Los par\u00e1metros espec\u00edficos de la soberan\u00eda del Brasil moderno se remontan al <a href=\"https:\/\/en.wikipedia.org\/wiki\/Treaty_of_Tordesillas\">Tratado de Tordesillas<\/a>, un acuerdo entre Portugal y Espa\u00f1a, Imperios que proceden del Sacro Imperio Romano Germ\u00e1nico, que consideraba que la soberan\u00eda ven\u00eda del cielo, a trav\u00e9s de un <a href=\"https:\/\/en.wikipedia.org\/wiki\/Divine_right_of_kings\">derecho divino<\/a> y la creencia en un Dios cat\u00f3lico. Esta creencia fue <a href=\"https:\/\/en.wikipedia.org\/wiki\/Catholic_Church_in_Brazil#:~:text=Catholicism%20was%20the%20predominant%20faith,Church%20has%20remained%20politically%20influential.\">impuesta<\/a> a los Pueblos Ind\u00edgenas de Brasil, a pesar de sus propias tradiciones de soberan\u00eda y espiritualidad, tradiciones que el art\u00edculo 231 de la Constituci\u00f3n brasile\u00f1a reconoce y supuestamente protege. Aunque ahora hablamos en t\u00e9rminos de pol\u00edtica, burocracia y derecho, cuando rastreamos las ra\u00edces de este sistema de pensamiento y acci\u00f3n, seguimos discutiendo las diferentes cosmovisiones y las diferentes concepciones de soberan\u00eda de los Pueblos Ind\u00edgenas de Brasil y de los colonos que llaman hogar a ese territorio.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">eco-nnect se enorgullece de formar parte de una alianza informal de individuos y grupos que se han unido para apoyar la situaci\u00f3n en Brasil. Esta alianza se ha centrado en una <a href=\"https:\/\/www.change.org\/p\/to-federal-authorities-of-brazil-to-protect-the-territorial-rights-of-indigenous-peoples\">petici\u00f3n<\/a> y una <a href=\"https:\/\/drive.google.com\/drive\/folders\/1pb2lV0EQ66VRES2WR5xNZGS-qKYCKL9P\">campa\u00f1a en las redes sociales<\/a> para presionar al Presidente del Senado Federal de Brasil, Rodrigo Pacheco -que tiene la capacidad de bloquear el PL 2903-, al tiempo que se recuerda a los Representantes del Senado Federal y a los Magistrados del Tribunal Supremo la responsabilidad que tienen actualmente. La situaci\u00f3n contin\u00faa, as\u00ed que por favor apoyemos a los Pueblos Ind\u00edgenas de Brasil; su <a href=\"https:\/\/www.iisd.org\/articles\/deep-dive\/indigenous-peoples-defending-environment-all\" class=\"broken_link\">importante<\/a> e inherente relaci\u00f3n con sus territorios; y el reconocimiento legal de su soberan\u00eda.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><i><span style=\"font-weight: 400;\">Anton Rivette es <\/span><\/i><a href=\"https:\/\/www.antonrivette.com\/words\"><i><span style=\"font-weight: 400;\">escritor<\/span><\/i><\/a><i><span style=\"font-weight: 400;\"> y <\/span><\/i><a href=\"https:\/\/www.instagram.com\/antonrivette\/\" class=\"broken_link\"><i><span style=\"font-weight: 400;\">fot\u00f3grafo.<\/span><\/i><\/a><i><span style=\"font-weight: 400;\"> Dirige el \u00e1rea de storytelling de eco-nnect.<\/span><\/i><\/p>\n<p><i><span style=\"font-weight: 400;\">Sarah Camhi es traductora y escritora. Hace parte del equipo de eco-nnect desde el 2020.<\/span><\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Reading Time: <\/span> <span class=\"rt-time\">21<\/span> <span class=\"rt-label rt-postfix\">min<\/span><\/span> Raposa-Serra do Sol, en el Estado de Roraima, al norte de Brasil, es una cadena de biomas conocida localmente como lavrado. En esta regi\u00f3n, el lavrado abarca praderas, sabanas esteparias, matorrales y zonas de peque\u00f1os bosques, que forman parte de una delicada red interconectada de ecosistemas que nutren y sustentan lo que a menudo se &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/eco-nnect.com\/es\/soberania-indigena-la-polemica-del-marco-temporal\/\"> <span class=\"screen-reader-text\">Soberan\u00eda ind\u00edgena: la pol\u00e9mica del Marco Temporal<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":25,"featured_media":14263,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"categories":[1927,2122,1933,1920,2123],"tags":[2202,2267,2270,2271,2272,2268,2273,2269,2201],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.2.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Soberan\u00eda ind\u00edgena: la pol\u00e9mica del Marco Temporal - eco-nnect<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eco-nnect.com\/es\/soberania-indigena-la-polemica-del-marco-temporal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Soberan\u00eda ind\u00edgena: la pol\u00e9mica del Marco Temporal - eco-nnect\" \/>\n<meta property=\"og:description\" content=\"Reading Time: 21 min Raposa-Serra do Sol, en el Estado de Roraima, al norte de Brasil, es una cadena de biomas conocida localmente como lavrado. En esta regi\u00f3n, el lavrado abarca praderas, sabanas esteparias, matorrales y zonas de peque\u00f1os bosques, que forman parte de una delicada red interconectada de ecosistemas que nutren y sustentan lo que a menudo se &hellip; Soberan\u00eda ind\u00edgena: la pol\u00e9mica del Marco Temporal Leer m\u00e1s &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eco-nnect.com\/es\/soberania-indigena-la-polemica-del-marco-temporal\/\" \/>\n<meta property=\"og:site_name\" content=\"eco-nnect\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-07T17:27:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-13T19:37:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/1599px-Contra_o_marco_temporal_Ato_PolC3ADtico_e_pronunciamento_dos_povos_indC3ADgenas_285217048639529.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1599\" \/>\n\t<meta property=\"og:image:height\" content=\"820\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Anton Rivette\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Anton Rivette\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"28 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/eco-nnect.com\/es\/soberania-indigena-la-polemica-del-marco-temporal\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/eco-nnect.com\/es\/soberania-indigena-la-polemica-del-marco-temporal\/\"},\"author\":{\"name\":\"Anton Rivette\",\"@id\":\"https:\/\/eco-nnect.com\/#\/schema\/person\/15234fcd4cccd4b0f48b2c6b6825a5d5\"},\"headline\":\"Soberan\u00eda ind\u00edgena: la pol\u00e9mica del Marco Temporal\",\"datePublished\":\"2023-07-07T17:27:53+00:00\",\"dateModified\":\"2023-08-13T19:37:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/eco-nnect.com\/es\/soberania-indigena-la-polemica-del-marco-temporal\/\"},\"wordCount\":6309,\"publisher\":{\"@id\":\"https:\/\/eco-nnect.com\/#organization\"},\"keywords\":[\"brasil\",\"demarcaci\u00f3n\",\"jair bolsonaro\",\"lula da silva\",\"marco temporal\",\"pueblos ind\u00edgenas\",\"raposa-serra do sol\",\"territorios ind\u00edgenas\",\"yanomami\"],\"articleSection\":[\"Biodiversidad\",\"Lecturas largas\",\"Pol\u00edtica\",\"Sin categorizar\",\"Historias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/eco-nnect.com\/es\/soberania-indigena-la-polemica-del-marco-temporal\/\",\"url\":\"https:\/\/eco-nnect.com\/es\/soberania-indigena-la-polemica-del-marco-temporal\/\",\"name\":\"Soberan\u00eda ind\u00edgena: la pol\u00e9mica del Marco Temporal - eco-nnect\",\"isPartOf\":{\"@id\":\"https:\/\/eco-nnect.com\/#website\"},\"datePublished\":\"2023-07-07T17:27:53+00:00\",\"dateModified\":\"2023-08-13T19:37:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/eco-nnect.com\/es\/soberania-indigena-la-polemica-del-marco-temporal\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/eco-nnect.com\/es\/soberania-indigena-la-polemica-del-marco-temporal\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/eco-nnect.com\/es\/soberania-indigena-la-polemica-del-marco-temporal\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/eco-nnect.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Soberan\u00eda ind\u00edgena: la pol\u00e9mica del Marco Temporal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/eco-nnect.com\/#website\",\"url\":\"https:\/\/eco-nnect.com\/\",\"name\":\"eco-nnect\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/eco-nnect.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/eco-nnect.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/eco-nnect.com\/#organization\",\"name\":\"eco-nnect\",\"url\":\"https:\/\/eco-nnect.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/eco-nnect.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/eco-nnect.com\/wp-content\/uploads\/2022\/02\/econnect.png\",\"contentUrl\":\"https:\/\/eco-nnect.com\/wp-content\/uploads\/2022\/02\/econnect.png\",\"width\":800,\"height\":132,\"caption\":\"eco-nnect\"},\"image\":{\"@id\":\"https:\/\/eco-nnect.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/eco-nnect.com\/#\/schema\/person\/15234fcd4cccd4b0f48b2c6b6825a5d5\",\"name\":\"Anton Rivette\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/eco-nnect.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ca987c50719adbd609f2252a315f5b8a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ca987c50719adbd609f2252a315f5b8a?s=96&d=mm&r=g\",\"caption\":\"Anton Rivette\"},\"url\":\"https:\/\/eco-nnect.com\/es\/author\/anton\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Soberan\u00eda ind\u00edgena: la pol\u00e9mica del Marco Temporal - eco-nnect","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eco-nnect.com\/es\/soberania-indigena-la-polemica-del-marco-temporal\/","og_locale":"es_ES","og_type":"article","og_title":"Soberan\u00eda ind\u00edgena: la pol\u00e9mica del Marco Temporal - eco-nnect","og_description":"Reading Time: 21 min Raposa-Serra do Sol, en el Estado de Roraima, al norte de Brasil, es una cadena de biomas conocida localmente como lavrado. En esta regi\u00f3n, el lavrado abarca praderas, sabanas esteparias, matorrales y zonas de peque\u00f1os bosques, que forman parte de una delicada red interconectada de ecosistemas que nutren y sustentan lo que a menudo se &hellip; Soberan\u00eda ind\u00edgena: la pol\u00e9mica del Marco Temporal Leer m\u00e1s &raquo;","og_url":"https:\/\/eco-nnect.com\/es\/soberania-indigena-la-polemica-del-marco-temporal\/","og_site_name":"eco-nnect","article_published_time":"2023-07-07T17:27:53+00:00","article_modified_time":"2023-08-13T19:37:50+00:00","og_image":[{"width":1599,"height":820,"url":"https:\/\/eco-nnect.com\/wp-content\/uploads\/2023\/07\/1599px-Contra_o_marco_temporal_Ato_PolC3ADtico_e_pronunciamento_dos_povos_indC3ADgenas_285217048639529.jpg","type":"image\/jpeg"}],"author":"Anton Rivette","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Anton Rivette","Tiempo de lectura":"28 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eco-nnect.com\/es\/soberania-indigena-la-polemica-del-marco-temporal\/#article","isPartOf":{"@id":"https:\/\/eco-nnect.com\/es\/soberania-indigena-la-polemica-del-marco-temporal\/"},"author":{"name":"Anton Rivette","@id":"https:\/\/eco-nnect.com\/#\/schema\/person\/15234fcd4cccd4b0f48b2c6b6825a5d5"},"headline":"Soberan\u00eda ind\u00edgena: la pol\u00e9mica del Marco Temporal","datePublished":"2023-07-07T17:27:53+00:00","dateModified":"2023-08-13T19:37:50+00:00","mainEntityOfPage":{"@id":"https:\/\/eco-nnect.com\/es\/soberania-indigena-la-polemica-del-marco-temporal\/"},"wordCount":6309,"publisher":{"@id":"https:\/\/eco-nnect.com\/#organization"},"keywords":["brasil","demarcaci\u00f3n","jair bolsonaro","lula da silva","marco temporal","pueblos ind\u00edgenas","raposa-serra do sol","territorios ind\u00edgenas","yanomami"],"articleSection":["Biodiversidad","Lecturas largas","Pol\u00edtica","Sin categorizar","Historias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/eco-nnect.com\/es\/soberania-indigena-la-polemica-del-marco-temporal\/","url":"https:\/\/eco-nnect.com\/es\/soberania-indigena-la-polemica-del-marco-temporal\/","name":"Soberan\u00eda ind\u00edgena: la pol\u00e9mica del Marco Temporal - eco-nnect","isPartOf":{"@id":"https:\/\/eco-nnect.com\/#website"},"datePublished":"2023-07-07T17:27:53+00:00","dateModified":"2023-08-13T19:37:50+00:00","breadcrumb":{"@id":"https:\/\/eco-nnect.com\/es\/soberania-indigena-la-polemica-del-marco-temporal\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eco-nnect.com\/es\/soberania-indigena-la-polemica-del-marco-temporal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/eco-nnect.com\/es\/soberania-indigena-la-polemica-del-marco-temporal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/eco-nnect.com\/es\/"},{"@type":"ListItem","position":2,"name":"Soberan\u00eda ind\u00edgena: la pol\u00e9mica del Marco Temporal"}]},{"@type":"WebSite","@id":"https:\/\/eco-nnect.com\/#website","url":"https:\/\/eco-nnect.com\/","name":"eco-nnect","description":"","publisher":{"@id":"https:\/\/eco-nnect.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eco-nnect.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/eco-nnect.com\/#organization","name":"eco-nnect","url":"https:\/\/eco-nnect.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/eco-nnect.com\/#\/schema\/logo\/image\/","url":"https:\/\/eco-nnect.com\/wp-content\/uploads\/2022\/02\/econnect.png","contentUrl":"https:\/\/eco-nnect.com\/wp-content\/uploads\/2022\/02\/econnect.png","width":800,"height":132,"caption":"eco-nnect"},"image":{"@id":"https:\/\/eco-nnect.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/eco-nnect.com\/#\/schema\/person\/15234fcd4cccd4b0f48b2c6b6825a5d5","name":"Anton Rivette","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/eco-nnect.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ca987c50719adbd609f2252a315f5b8a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ca987c50719adbd609f2252a315f5b8a?s=96&d=mm&r=g","caption":"Anton Rivette"},"url":"https:\/\/eco-nnect.com\/es\/author\/anton\/"}]}},"_links":{"self":[{"href":"https:\/\/eco-nnect.com\/es\/wp-json\/wp\/v2\/posts\/14431"}],"collection":[{"href":"https:\/\/eco-nnect.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eco-nnect.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eco-nnect.com\/es\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/eco-nnect.com\/es\/wp-json\/wp\/v2\/comments?post=14431"}],"version-history":[{"count":2,"href":"https:\/\/eco-nnect.com\/es\/wp-json\/wp\/v2\/posts\/14431\/revisions"}],"predecessor-version":[{"id":14496,"href":"https:\/\/eco-nnect.com\/es\/wp-json\/wp\/v2\/posts\/14431\/revisions\/14496"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eco-nnect.com\/es\/wp-json\/wp\/v2\/media\/14263"}],"wp:attachment":[{"href":"https:\/\/eco-nnect.com\/es\/wp-json\/wp\/v2\/media?parent=14431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eco-nnect.com\/es\/wp-json\/wp\/v2\/categories?post=14431"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eco-nnect.com\/es\/wp-json\/wp\/v2\/tags?post=14431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}