{"id":10529,"date":"2022-07-25T15:20:07","date_gmt":"2022-07-25T15:20:07","guid":{"rendered":"https:\/\/eco-nnect.com\/?p=10529"},"modified":"2022-07-26T12:53:42","modified_gmt":"2022-07-26T12:53:42","slug":"innovaciones-beneficiosas-para-los-corales-marinos","status":"publish","type":"post","link":"https:\/\/eco-nnect.com\/es\/innovaciones-beneficiosas-para-los-corales-marinos\/","title":{"rendered":"Innovaciones beneficiosas para los corales marinos"},"content":{"rendered":"<span class=\"rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Reading Time: <\/span> <span class=\"rt-time\">3<\/span> <span class=\"rt-label rt-postfix\">min<\/span><\/span><h1>Arrecifes de coral<\/h1>\n<p>&nbsp;<\/p>\n<p>Los arrecifes de coral sufren hoy las consecuencias del cambio clim\u00e1tico provocado por el hombre. El calentamiento global, y con ello la subida de las temperaturas es solo uno de los muchos factores que afectan negativamente a los corales marinos. Por ende, los peces y la vida marina que se alimenta de ellos, y sus algas se ven enormemente afectados.\u00a0El \u00faltimo informe de la Autoridad del Parque Marino de la Gran Barrera de Coral (GBRMPA) advierte de la urgencia \u00a0de la crisis clim\u00e1tica, y el apoyo necesario para mejorar estos h\u00e1bitats vitales. Afortunadamente existen empresas, start-ups, y organizaciones que tienen como objetivos principal la preservaci\u00f3n de los oc\u00e9anos.<\/p>\n<p>&nbsp;<\/p>\n<h2><b>1- \u201cHope Reef\u201d un proyecto de Sheba<\/b><\/h2>\n<h3><b>Apuesta de las empresas por el abastecimiento sostenible<span class=\"Apple-converted-space\">\u00a0<\/span><\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><b>\u201c<\/b>Sheba\u201d, la marca de comida para gatos, -parte de la multinacional americana Mars- depende del pescado de los oc\u00e9anos. Como muchas otras empresas, restaurar los oc\u00e9anos es primordial para ellos, y para construir una cadena de suministro sostenible. Con este proyecto, se utilizan fragmentos de coral unidos a estrellas de arrecife hechas por el hombre. As\u00ed, estas estructuras ayudan a que el arrecife crezca, y atraiga vida marina.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>\u201cLa empresa se ha comprometido a un plan de proyecto de 10 a\u00f1os, con 840 estrellas de arrecife ya a\u00f1adidas al fondo marino y otras previstas en arrecifes cercanos a Australia, M\u00e9xico y las Seychelles.\u201d<\/p>\n<p>Adem\u00e1s, esta marca se ha asociado con The Nature Conservancy creando un canal de Youtube monetizado. Mira este video para ayudar a recaudar fondos para otros proyectos de restauraci\u00f3n de arrecifes de coral.<\/p>\n<div class=\"epyt-video-wrapper\"><div  id=\"_ytid_80968\"  width=\"800\" height=\"450\"  data-origwidth=\"800\" data-origheight=\"450\" data-facadesrc=\"https:\/\/www.youtube.com\/embed\/Nfhq4b4p1I0?enablejsapi=1&autoplay=0&cc_load_policy=0&cc_lang_pref=&iv_load_policy=1&loop=0&modestbranding=0&rel=0&fs=1&playsinline=0&autohide=2&theme=dark&color=red&controls=1&\" class=\"__youtube_prefs__ epyt-facade no-lazyload\" data-epautoplay=\"1\" ><img data-spai-excluded=\"true\" class=\"epyt-facade-poster skip-lazy\" loading=\"lazy\"  alt=\"YouTube player\"  src=\"https:\/\/i.ytimg.com\/vi\/Nfhq4b4p1I0\/maxresdefault.jpg\"  \/><button class=\"epyt-facade-play\" aria-label=\"Play\"><svg data-no-lazy=\"1\" height=\"100%\" version=\"1.1\" viewBox=\"0 0 68 48\" width=\"100%\"><path class=\"ytp-large-play-button-bg\" d=\"M66.52,7.74c-0.78-2.93-2.49-5.41-5.42-6.19C55.79,.13,34,0,34,0S12.21,.13,6.9,1.55 C3.97,2.33,2.27,4.81,1.48,7.74C0.06,13.05,0,24,0,24s0.06,10.95,1.48,16.26c0.78,2.93,2.49,5.41,5.42,6.19 C12.21,47.87,34,48,34,48s21.79-0.13,27.1-1.55c2.93-0.78,4.64-3.26,5.42-6.19C67.94,34.95,68,24,68,24S67.94,13.05,66.52,7.74z\" fill=\"#f00\"><\/path><path d=\"M 45,24 27,14 27,34\" fill=\"#fff\"><\/path><\/svg><\/button><\/div><\/div>\n<blockquote><p><a href=\"https:\/\/www.msn.com\/en-us\/weather\/topstories\/great-barrier-reef-91-of-reefs-surveyed-suffered-coral-bleaching-in-2022\/ar-AAX8Mcf\">\u201cEl calentamiento de las aguas provoca el deterioro de los corales. La decadencia de la Gran Barrera de Coral.\u201d<\/a><\/p><\/blockquote>\n<h2>2- <b>\u201cReCoral\u201d un proyecto de \u00d8rsted<\/b><\/h2>\n<h3><b>Utilizar parques e\u00f3licos para ayudar a los arrecifes de coral<span class=\"Apple-converted-space\">\u00a0<\/span><\/b><\/h3>\n<p>&nbsp;<\/p>\n<p>Este proyecto, liderado por la empresa de energ\u00eda Danesa \u00d8rsted pretende ofrecer un lugar mejor para crecer y mantener corales. Esta empresa recogi\u00f3 huevos de coral en una playa cerca de Taiwan y los incubaron en un laboratorio hasta que se convirtieron en larvas de coral visibles. Tras ello, las llevaron a un parque e\u00f3lico donde gracias a la temperatura base y m\u00e1s estable, los corales crecieron m\u00e1s sanos y con menores riesgos.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>El objetivo es ofrecer un \u201crefugio seguro\u201d y trasladar este proyecto a otras bases e\u00f3licas donde puedan crecer mas corales. Con esto se mantendr\u00edan poblaciones de peces m\u00e1s sanas.<\/p>\n<p>Visita <a href=\"https:\/\/orsted.com\">aqu\u00ed<\/a> su p\u00e1gina Web.<\/p>\n<p><a href=\"http:\/\/https:\/\/orsted.com \" class=\"broken_link\"><img decoding=\"async\" loading=\"lazy\" class=\" wp-image-10530 aligncenter\" src=\"https:\/\/eco-nnect.com\/wp-content\/uploads\/2022\/07\/Captura-de-pantalla-2022-07-25-a-las-12.07.11-300x171.png\" alt=\"\" width=\"415\" height=\"237\" srcset=\"https:\/\/eco-nnect.com\/wp-content\/uploads\/2022\/07\/Captura-de-pantalla-2022-07-25-a-las-12.07.11-300x171.png 300w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2022\/07\/Captura-de-pantalla-2022-07-25-a-las-12.07.11-600x343.png 600w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2022\/07\/Captura-de-pantalla-2022-07-25-a-las-12.07.11-1024x585.png 1024w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2022\/07\/Captura-de-pantalla-2022-07-25-a-las-12.07.11-768x438.png 768w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2022\/07\/Captura-de-pantalla-2022-07-25-a-las-12.07.11.png 1058w\" sizes=\"(max-width: 415px) 100vw, 415px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2>3-<b><span class=\"Apple-converted-space\">\u00a0<\/span>Cuero a partir de Pez de Le\u00f3n, un proyecto de Inversa<\/b><\/h2>\n<h3><b>Un start-up en Florida utiliza la moda para combatir el peligro de este pez en los corales.<span class=\"Apple-converted-space\">\u00a0<\/span><\/b><\/h3>\n<p>&nbsp;<\/p>\n<p>Al parecer, el Pez de Le\u00f3n se considera una especie muy invasiva en las aguas atl\u00e1nticas de Florida. Este depredador tiene un impacto en la salud de los arrecifes de coral y la vida que sustentan. Inversa, una marca de moda sostenible basada en Florida, pretende reducir la presi\u00f3n sobre los ecosistemas marinos, y con este proyecto ofrecer una alternativa al cuero de vaca.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>La empresa colabora ya con otras marcas como <a href=\"https:\/\/p448.com\/collections\/sustainable\/Type:-Women?page=2\">P448<\/a> (marca de zapatos italiana), y <a href=\"https:\/\/www.tetonleathercompany.com\/#\/\">Teton Leather<\/a>, que se sumar\u00e1n a la producci\u00f3n de accesorios con la piel de pez de le\u00f3n. Inversa fue adem\u00e1s finalista de la subvenci\u00f3n Ocean Resilience Innovation Challenge de la Ocean Risk and Resilience Action Alliance (ORRAA). No s\u00f3lo es un proyecto innovador si no que ayudan al medio ambiente eliminando un peligro en los oc\u00e9anos, y dejando una huella muy peque\u00f1a en el proceso. Inversa solo utiliza 200ml de agua por piel.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Visita <a href=\"https:\/\/www.inversaleathers.com\">aqu\u00ed<\/a> su p\u00e1gina Web.<\/p>\n<div id='gallery-1' class='gallery galleryid-10529 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/eco-nnect.com\/es\/innovaciones-beneficiosas-para-los-corales-marinos\/captura-de-pantalla-2022-07-25-a-las-16-54-03\/'><img width=\"150\" height=\"150\" src=\"https:\/\/eco-nnect.com\/wp-content\/uploads\/2022\/07\/Captura-de-pantalla-2022-07-25-a-las-16.54.03-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" aria-describedby=\"gallery-1-10543\" srcset=\"https:\/\/eco-nnect.com\/wp-content\/uploads\/2022\/07\/Captura-de-pantalla-2022-07-25-a-las-16.54.03-150x150.png 150w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2022\/07\/Captura-de-pantalla-2022-07-25-a-las-16.54.03-300x300.png 300w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2022\/07\/Captura-de-pantalla-2022-07-25-a-las-16.54.03-100x100.png 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-10543'>\n\t\t\t\tPez de Le\u00f3n\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/eco-nnect.com\/es\/innovaciones-beneficiosas-para-los-corales-marinos\/captura-de-pantalla-2022-07-25-a-las-16-48-48\/'><img width=\"150\" height=\"150\" src=\"https:\/\/eco-nnect.com\/wp-content\/uploads\/2022\/07\/Captura-de-pantalla-2022-07-25-a-las-16.48.48-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" aria-describedby=\"gallery-1-10541\" srcset=\"https:\/\/eco-nnect.com\/wp-content\/uploads\/2022\/07\/Captura-de-pantalla-2022-07-25-a-las-16.48.48-150x150.png 150w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2022\/07\/Captura-de-pantalla-2022-07-25-a-las-16.48.48-300x300.png 300w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2022\/07\/Captura-de-pantalla-2022-07-25-a-las-16.48.48-100x100.png 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-10541'>\n\t\t\t\tP448 shoes\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/eco-nnect.com\/es\/innovaciones-beneficiosas-para-los-corales-marinos\/captura-de-pantalla-2022-07-25-a-las-16-47-48\/'><img width=\"150\" height=\"150\" src=\"https:\/\/eco-nnect.com\/wp-content\/uploads\/2022\/07\/Captura-de-pantalla-2022-07-25-a-las-16.47.48-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" aria-describedby=\"gallery-1-10539\" srcset=\"https:\/\/eco-nnect.com\/wp-content\/uploads\/2022\/07\/Captura-de-pantalla-2022-07-25-a-las-16.47.48-150x150.png 150w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2022\/07\/Captura-de-pantalla-2022-07-25-a-las-16.47.48-300x300.png 300w, https:\/\/eco-nnect.com\/wp-content\/uploads\/2022\/07\/Captura-de-pantalla-2022-07-25-a-las-16.47.48-100x100.png 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-10539'>\n\t\t\t\tTeton Leather\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p><span class=\"rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Reading Time: <\/span> <span class=\"rt-time\">3<\/span> <span class=\"rt-label rt-postfix\">min<\/span><\/span> Arrecifes de coral &nbsp; Los arrecifes de coral sufren hoy las consecuencias del cambio clim\u00e1tico provocado por el hombre. El calentamiento global, y con ello la subida de las temperaturas es solo uno de los muchos factores que afectan negativamente a los corales marinos. Por ende, los peces y la vida marina que se alimenta &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/eco-nnect.com\/es\/innovaciones-beneficiosas-para-los-corales-marinos\/\"> <span class=\"screen-reader-text\">Innovaciones beneficiosas para los corales marinos<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":7,"featured_media":10545,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"gallery","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"categories":[1927,1931],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.2.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Innovaciones beneficiosas para los corales marinos - eco-nnect<\/title>\n<meta name=\"description\" content=\"Los arrecifes de coral sufren hoy m\u00e1s que nunca. Descubre las innovaciones que exploran mejorar esta situacion en los corales de los oc\u00e9anos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eco-nnect.com\/es\/innovaciones-beneficiosas-para-los-corales-marinos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Innovaciones beneficiosas para los corales marinos - eco-nnect\" \/>\n<meta property=\"og:description\" content=\"Los arrecifes de coral sufren hoy m\u00e1s que nunca. Descubre las innovaciones que exploran mejorar esta situacion en los corales de los oc\u00e9anos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eco-nnect.com\/es\/innovaciones-beneficiosas-para-los-corales-marinos\/\" \/>\n<meta property=\"og:site_name\" content=\"eco-nnect\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-25T15:20:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-26T12:53:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eco-nnect.com\/wp-content\/uploads\/2022\/07\/Captura-de-pantalla-2022-07-25-a-las-12.57.02-1024x430.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"430\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Mar\u00eda S\u00e1nchez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mar\u00eda S\u00e1nchez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/eco-nnect.com\/es\/innovaciones-beneficiosas-para-los-corales-marinos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/eco-nnect.com\/es\/innovaciones-beneficiosas-para-los-corales-marinos\/\"},\"author\":{\"name\":\"Mar\u00eda S\u00e1nchez\",\"@id\":\"https:\/\/eco-nnect.com\/#\/schema\/person\/abb9dd660cbda600530c76b511b63c9f\"},\"headline\":\"Innovaciones beneficiosas para los corales marinos\",\"datePublished\":\"2022-07-25T15:20:07+00:00\",\"dateModified\":\"2022-07-26T12:53:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/eco-nnect.com\/es\/innovaciones-beneficiosas-para-los-corales-marinos\/\"},\"wordCount\":648,\"publisher\":{\"@id\":\"https:\/\/eco-nnect.com\/#organization\"},\"articleSection\":[\"Biodiversidad\",\"Innovaci\u00f3n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/eco-nnect.com\/es\/innovaciones-beneficiosas-para-los-corales-marinos\/\",\"url\":\"https:\/\/eco-nnect.com\/es\/innovaciones-beneficiosas-para-los-corales-marinos\/\",\"name\":\"Innovaciones beneficiosas para los corales marinos - eco-nnect\",\"isPartOf\":{\"@id\":\"https:\/\/eco-nnect.com\/#website\"},\"datePublished\":\"2022-07-25T15:20:07+00:00\",\"dateModified\":\"2022-07-26T12:53:42+00:00\",\"description\":\"Los arrecifes de coral sufren hoy m\u00e1s que nunca. Descubre las innovaciones que exploran mejorar esta situacion en los corales de los oc\u00e9anos.\",\"breadcrumb\":{\"@id\":\"https:\/\/eco-nnect.com\/es\/innovaciones-beneficiosas-para-los-corales-marinos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/eco-nnect.com\/es\/innovaciones-beneficiosas-para-los-corales-marinos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/eco-nnect.com\/es\/innovaciones-beneficiosas-para-los-corales-marinos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/eco-nnect.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Innovaciones beneficiosas para los corales marinos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/eco-nnect.com\/#website\",\"url\":\"https:\/\/eco-nnect.com\/\",\"name\":\"eco-nnect\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/eco-nnect.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/eco-nnect.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/eco-nnect.com\/#organization\",\"name\":\"eco-nnect\",\"url\":\"https:\/\/eco-nnect.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/eco-nnect.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/eco-nnect.com\/wp-content\/uploads\/2022\/02\/econnect.png\",\"contentUrl\":\"https:\/\/eco-nnect.com\/wp-content\/uploads\/2022\/02\/econnect.png\",\"width\":800,\"height\":132,\"caption\":\"eco-nnect\"},\"image\":{\"@id\":\"https:\/\/eco-nnect.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/eco-nnect.com\/#\/schema\/person\/abb9dd660cbda600530c76b511b63c9f\",\"name\":\"Mar\u00eda S\u00e1nchez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/eco-nnect.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4805647540ddf7224a47bff32c9bbfd9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4805647540ddf7224a47bff32c9bbfd9?s=96&d=mm&r=g\",\"caption\":\"Mar\u00eda S\u00e1nchez\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/mariasanchezfaus\/\"],\"url\":\"https:\/\/eco-nnect.com\/es\/author\/msanchezf-ieu2017student-ie-edu\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Innovaciones beneficiosas para los corales marinos - eco-nnect","description":"Los arrecifes de coral sufren hoy m\u00e1s que nunca. Descubre las innovaciones que exploran mejorar esta situacion en los corales de los oc\u00e9anos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eco-nnect.com\/es\/innovaciones-beneficiosas-para-los-corales-marinos\/","og_locale":"es_ES","og_type":"article","og_title":"Innovaciones beneficiosas para los corales marinos - eco-nnect","og_description":"Los arrecifes de coral sufren hoy m\u00e1s que nunca. Descubre las innovaciones que exploran mejorar esta situacion en los corales de los oc\u00e9anos.","og_url":"https:\/\/eco-nnect.com\/es\/innovaciones-beneficiosas-para-los-corales-marinos\/","og_site_name":"eco-nnect","article_published_time":"2022-07-25T15:20:07+00:00","article_modified_time":"2022-07-26T12:53:42+00:00","og_image":[{"width":1024,"height":430,"url":"https:\/\/eco-nnect.com\/wp-content\/uploads\/2022\/07\/Captura-de-pantalla-2022-07-25-a-las-12.57.02-1024x430.png","type":"image\/png"}],"author":"Mar\u00eda S\u00e1nchez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Mar\u00eda S\u00e1nchez","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eco-nnect.com\/es\/innovaciones-beneficiosas-para-los-corales-marinos\/#article","isPartOf":{"@id":"https:\/\/eco-nnect.com\/es\/innovaciones-beneficiosas-para-los-corales-marinos\/"},"author":{"name":"Mar\u00eda S\u00e1nchez","@id":"https:\/\/eco-nnect.com\/#\/schema\/person\/abb9dd660cbda600530c76b511b63c9f"},"headline":"Innovaciones beneficiosas para los corales marinos","datePublished":"2022-07-25T15:20:07+00:00","dateModified":"2022-07-26T12:53:42+00:00","mainEntityOfPage":{"@id":"https:\/\/eco-nnect.com\/es\/innovaciones-beneficiosas-para-los-corales-marinos\/"},"wordCount":648,"publisher":{"@id":"https:\/\/eco-nnect.com\/#organization"},"articleSection":["Biodiversidad","Innovaci\u00f3n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/eco-nnect.com\/es\/innovaciones-beneficiosas-para-los-corales-marinos\/","url":"https:\/\/eco-nnect.com\/es\/innovaciones-beneficiosas-para-los-corales-marinos\/","name":"Innovaciones beneficiosas para los corales marinos - eco-nnect","isPartOf":{"@id":"https:\/\/eco-nnect.com\/#website"},"datePublished":"2022-07-25T15:20:07+00:00","dateModified":"2022-07-26T12:53:42+00:00","description":"Los arrecifes de coral sufren hoy m\u00e1s que nunca. Descubre las innovaciones que exploran mejorar esta situacion en los corales de los oc\u00e9anos.","breadcrumb":{"@id":"https:\/\/eco-nnect.com\/es\/innovaciones-beneficiosas-para-los-corales-marinos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eco-nnect.com\/es\/innovaciones-beneficiosas-para-los-corales-marinos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/eco-nnect.com\/es\/innovaciones-beneficiosas-para-los-corales-marinos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/eco-nnect.com\/es\/"},{"@type":"ListItem","position":2,"name":"Innovaciones beneficiosas para los corales marinos"}]},{"@type":"WebSite","@id":"https:\/\/eco-nnect.com\/#website","url":"https:\/\/eco-nnect.com\/","name":"eco-nnect","description":"","publisher":{"@id":"https:\/\/eco-nnect.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eco-nnect.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/eco-nnect.com\/#organization","name":"eco-nnect","url":"https:\/\/eco-nnect.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/eco-nnect.com\/#\/schema\/logo\/image\/","url":"https:\/\/eco-nnect.com\/wp-content\/uploads\/2022\/02\/econnect.png","contentUrl":"https:\/\/eco-nnect.com\/wp-content\/uploads\/2022\/02\/econnect.png","width":800,"height":132,"caption":"eco-nnect"},"image":{"@id":"https:\/\/eco-nnect.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/eco-nnect.com\/#\/schema\/person\/abb9dd660cbda600530c76b511b63c9f","name":"Mar\u00eda S\u00e1nchez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/eco-nnect.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/4805647540ddf7224a47bff32c9bbfd9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4805647540ddf7224a47bff32c9bbfd9?s=96&d=mm&r=g","caption":"Mar\u00eda S\u00e1nchez"},"sameAs":["https:\/\/www.linkedin.com\/in\/mariasanchezfaus\/"],"url":"https:\/\/eco-nnect.com\/es\/author\/msanchezf-ieu2017student-ie-edu\/"}]}},"_links":{"self":[{"href":"https:\/\/eco-nnect.com\/es\/wp-json\/wp\/v2\/posts\/10529"}],"collection":[{"href":"https:\/\/eco-nnect.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eco-nnect.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eco-nnect.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/eco-nnect.com\/es\/wp-json\/wp\/v2\/comments?post=10529"}],"version-history":[{"count":6,"href":"https:\/\/eco-nnect.com\/es\/wp-json\/wp\/v2\/posts\/10529\/revisions"}],"predecessor-version":[{"id":10554,"href":"https:\/\/eco-nnect.com\/es\/wp-json\/wp\/v2\/posts\/10529\/revisions\/10554"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eco-nnect.com\/es\/wp-json\/wp\/v2\/media\/10545"}],"wp:attachment":[{"href":"https:\/\/eco-nnect.com\/es\/wp-json\/wp\/v2\/media?parent=10529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eco-nnect.com\/es\/wp-json\/wp\/v2\/categories?post=10529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eco-nnect.com\/es\/wp-json\/wp\/v2\/tags?post=10529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}